{"id":4234,"count":2,"description":"","link":"https:\/\/ticketsibiza.com\/nl\/dj\/oliver-koletzki\/","name":"Oliver Koletzki","slug":"oliver-koletzki","taxonomy":"dj","meta":[],"acf":{"dj_image":null,"featured_dj":false},"uncode_term_thumbnail_id":"585348","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/dj\/4234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/dj"}],"about":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/taxonomies\/dj"}],"wp:post_type":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/class?dj=4234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}