{"id":1148089,"date":"2026-04-23T17:36:55","date_gmt":"2026-04-23T16:36:55","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/la-disturbia-eden-2026-07-09\/"},"modified":"2026-05-26T15:46:59","modified_gmt":"2026-05-26T14:46:59","slug":"la-disturbia-eden-2026-07-09","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/nl\/event\/la-disturbia-eden-2026-07-09\/","title":{"rendered":"La Disturbia"},"content":{"rendered":"<p>La Disturbia neemt de donderdagen in Eden over van begin juli tot eind augustus 2026, een run van acht weken tijdens het hoogseizoen. De residency richt zich op de hardere, meer stuwende kant van techhouse en tribal, waarmee het een nachtelijke identiteit cre\u00ebert die afwijkt van de overige programmering van Eden. La Disturbia heeft een trouwe aanhang opgebouwd in heel Spanje en Ibiza door de focus op energie en een sterke line-up van resident-dj's, en de plek in Eden biedt het geluidssysteem en de ruimte in het hoogseizoen die daar perfect bij passen. Verwacht wisselende gasten gedurende de hele periode, met een programmering die stevig geworteld is in tribal tech en hard-grooving house. Een goede optie voor de donderdag voor wie houdt van een clubavond met pit in plaats van gepolijste deuntjes.    <\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Line-up<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/miguel-bastida\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Miguel Bastida\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Miguel Bastida<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/plastik-funk\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Plastik Funk\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Plastik Funk<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/stban\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Stban\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Stban<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/darios-nunes\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Darios Nunes\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Darios Nunes<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/antonin\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Antonin\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Antonin<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/don-juan\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Don Juan\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Don Juan<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Miguel Bastida<br \/>\nPlastik Funk<br \/>\nStban<br \/>\nDarios Nunes<br \/>\nAntonin<br \/>\nDon Juan<\/p>\n","protected":false},"template":"","wcs-type":[3813,3958,12602,307],"dj":[12671,15406,15407,15620,15621,15622],"class_list":["post-1148089","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-thursday","wcs-type-3958","wcs-type-la-disturbia","wcs-type-superclub","wcs-room-eden","dj-plastik-funk","dj-stban","dj-don-juan","dj-miguel-bastida","dj-darios-nunes","dj-antonin"],"acf":[],"_wcs_timestamp":"1783637940","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/class\/1148089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/media\/1130089"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/media?parent=1148089"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/wcs-type?post=1148089"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/dj?post=1148089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}