{"id":1136115,"date":"2026-03-30T13:04:58","date_gmt":"2026-03-30T12:04:58","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/you-know-the-vibes-es-paradis-2026-06-15\/"},"modified":"2026-03-30T13:04:58","modified_gmt":"2026-03-30T12:04:58","slug":"you-know-the-vibes-es-paradis-2026-06-15","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/nl\/event\/you-know-the-vibes-es-paradis-2026-06-15\/","title":{"rendered":"You Know The Vibes"},"content":{"rendered":"<p>You Know The Vibes is de vaste zondagavond in Es Paradis en brengt een mix van urban, R&amp;B en commerci\u00eble dancemuziek naar de iconische locatie in San Antonio. Het feest loopt het hele seizoen door, van eind april tot eind oktober, en biedt een vaste wekelijkse optie voor wie op zondagavond de voorkeur geeft aan een meer mainstream soundtrack. De amfitheater-setting van Es Paradis geeft elke avond daar een speciaal tintje.  <\/p>\n<div class=\"wcs-lineup wcs-lineup--text\"><h3 class=\"wcs-lineup__title\">Line-up<\/h3><div class=\"wcs-lineup__excerpt\"><p>Line-up volgt<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Line-up volgt<\/p>\n","protected":false},"template":"","wcs-type":[3810,3958,10564],"dj":[],"class_list":["post-1136115","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-monday","wcs-type-3958","wcs-type-you-know-the-vibes","wcs-room-es-paradis"],"acf":[],"_wcs_timestamp":"1781563500","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/class\/1136115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/media\/1001681"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/media?parent=1136115"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/wcs-type?post=1136115"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/dj?post=1136115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}