{"id":1123001,"date":"2026-03-10T12:49:05","date_gmt":"2026-03-10T12:49:05","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/solid-grooves-dc10-2026-07-02\/"},"modified":"2026-05-07T14:22:36","modified_gmt":"2026-05-07T13:22:36","slug":"solid-grooves-dc10-2026-07-02","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/nl\/event\/solid-grooves-dc10-2026-07-02\/","title":{"rendered":"Solid grooves"},"content":{"rendered":"<p>Solid Grooves keert terug naar zijn spirituele thuisbasis in DC10 voor weer een seizoen vol rauw, no-nonsense clubben. <\/p>\n<p>Opgericht door Michael Bibi, is het feest uitgegroeid tot een van de meest gerespecteerde wekelijkse residencies van het eiland, met een publiek dat in de eerste plaats voor de muziek komt en al het andere op de tweede plek zet. De Garden-setting bij DC10 biedt de sobere openluchtomgeving die perfect past bij de sound van Solid Grooves: diepe, stuwende house en techno zonder poespas.  <\/p>\n<p>Elke donderdag van juni tot en met oktober.<\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Line-up<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/ben-sterling\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2025\/08\/ben-sterling-150x150.jpeg\" alt=\"Ben Sterling\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Ben Sterling<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/cristina-lazic\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Cristina Lazic\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Cristina Lazic<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/jamback\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Jamback\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Jamback<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/marco-carola\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2022\/09\/marco-carola-150x150.jpeg\" alt=\"Marco Carola\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Marco Carola<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/patrick-topping\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/patrick-topping-150x150.jpg\" alt=\"Patrick topping\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Patrick topping<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/pawsa\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2022\/09\/pawsa-150x150.jpg\" alt=\"PAWSA\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">PAWSA<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/silvie-loto\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Silvie Loto\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Silvie Loto<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ben Sterling<br \/>\nCristina Lazic<br \/>\nJamback<br \/>\nMarco Carola<br \/>\nPatrick Topping<br \/>\nPAWSA<br \/>\nSilvie Loto<\/p>\n","protected":false},"template":"","wcs-type":[158,3813,3958],"dj":[6320,6949,7426,4113,4231,4686,5064],"class_list":["post-1123001","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-solid-grooves","wcs-type-thursday","wcs-type-3958","wcs-room-dc10","dj-ben-sterling","dj-silvie-loto","dj-pawsa","dj-marco-carola","dj-jamback","dj-patrick-topping","dj-cristina-lazic"],"acf":[],"_wcs_timestamp":"1783011600","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/class\/1123001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/media\/994679"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/media?parent=1123001"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/wcs-type?post=1123001"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/dj?post=1123001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}