{"id":1109212,"date":"2026-02-05T16:17:30","date_gmt":"2026-02-05T16:17:30","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/bresh-amnesia-2026-07-04\/"},"modified":"2026-02-05T16:17:30","modified_gmt":"2026-02-05T16:17:30","slug":"bresh-amnesia-2026-07-04","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/nl\/event\/bresh-amnesia-2026-07-04\/","title":{"rendered":"BRESH"},"content":{"rendered":"<p>Het meest kleurrijke feest ter wereld is terug op het Witte Eiland! BRESH keert elke zaterdag deze zomer terug naar Amnesia en brengt zijn feelgood chaos en genre-overstijgende soundtrack naar een van Ibiza&#8217;s meest legendarische dancefloors. <\/p>\n<p>Verwacht een euforische mix van reggaeton, pop, disco, hiphop en rock, levendige visuals, bloembommen en een publiek dat helemaal draait om goede vibes en nul pretentie. Geboren in Buenos Aires en nu een wereldwijd fenomeen, BRESH is meer dan een feest &#8211; het is een viering van vrijheid, vriendschap en dansen alsof niemand kijkt. Laat de glitter maar regenen.  <\/p>\n<div class=\"wcs-lineup wcs-lineup--text\"><h3 class=\"wcs-lineup__title\">Line-up<\/h3><div class=\"wcs-lineup__excerpt\"><p>Line-up volgt<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Line-up volgt<\/p>\n","protected":false},"template":"","wcs-type":[3958,307,2103,3815],"dj":[],"class_list":["post-1109212","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-3958","wcs-type-superclub","wcs-type-bresh","wcs-type-saturday","wcs-room-amnesia"],"acf":[],"_wcs_timestamp":"1783205940","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/class\/1109212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/media\/1104511"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/media?parent=1109212"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/wcs-type?post=1109212"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/dj?post=1109212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}