{"id":1100104,"date":"2026-02-03T11:54:39","date_gmt":"2026-02-03T11:54:39","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/aftersun-boat-party-playa-den-bossa-boat-parties-2026-08-18\/"},"modified":"2026-02-05T10:22:58","modified_gmt":"2026-02-05T10:22:58","slug":"aftersun-boat-party-playa-den-bossa-boat-parties-2026-08-18","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/nl\/event\/aftersun-boat-party-playa-den-bossa-boat-parties-2026-08-18\/","title":{"rendered":"Aftersun Boat Party"},"content":{"rendered":"<p>Aftersun is terug in 2026 \u2013 en het is nog steeds het heetste nieuwe Ibiza Bootfeest <\/p>\n<p>Ga mee met 300+ feestliefhebbers voor een all-inclusive zonsondergangcruise die je niet zult vergeten, die tot zes keer per week de hele zomer vertrekt vanaf Playa d'en Bossa.<\/p>\n<p>Verwacht non-stop vibes met geweldige muziek, een open bar met bier &amp; sangria, een verfrissende zwemstop en de beste plaatsen voor Ibiza&#8217;s iconische zonsondergang \u2013 allemaal met een bruisende menigte en onverslaanbare energie.<\/p>\n<p>Tickets zijn alleen online verkrijgbaar \u2013 bestel de jouwe nu voordat ze op zijn!<\/p>\n<h4><div class=\"wcs-lineup wcs-lineup--text\"><h3 class=\"wcs-lineup__title\">Line-up<\/h3><div class=\"wcs-lineup__excerpt\"><p>Resident DJ&#039;s<\/p>\n<\/div><\/div><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Resident DJ's<\/p>\n","protected":false},"template":"","wcs-type":[308,1537,3811,3958],"dj":[],"class_list":["post-1100104","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-boat-party","wcs-type-aftersun-boat-party","wcs-type-tuesday","wcs-type-3958","wcs-room-playa-den-bossa-boat-parties"],"acf":[],"_wcs_timestamp":"1787076900","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/class\/1100104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/media\/994758"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/media?parent=1100104"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/wcs-type?post=1100104"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/dj?post=1100104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}