{"id":1099717,"date":"2026-02-03T11:43:18","date_gmt":"2026-02-03T11:43:18","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/aftersun-boat-party-playa-den-bossa-boat-parties-2026-07-18\/"},"modified":"2026-02-05T10:12:59","modified_gmt":"2026-02-05T10:12:59","slug":"aftersun-boat-party-playa-den-bossa-boat-parties-2026-07-18","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/nl\/event\/aftersun-boat-party-playa-den-bossa-boat-parties-2026-07-18\/","title":{"rendered":"Aftersun Boat Party"},"content":{"rendered":"<p>Aftersun is terug in 2026 \u2013 en het is nog steeds het heetste nieuwe Ibiza Bootfeest <\/p>\n<p>Ga mee met 300+ feestliefhebbers voor een all-inclusive zonsondergangcruise die je niet zult vergeten, die tot zes keer per week de hele zomer vertrekt vanaf Playa d'en Bossa.<\/p>\n<p>Verwacht non-stop vibes met geweldige muziek, een open bar met bier &amp; sangria, een verfrissende zwemstop en de beste plaatsen voor Ibiza&#8217;s iconische zonsondergang \u2013 allemaal met een bruisende menigte en onverslaanbare energie.<\/p>\n<p>Tickets zijn alleen online verkrijgbaar \u2013 bestel de jouwe nu voordat ze op zijn!<\/p>\n<h4><div class=\"wcs-lineup wcs-lineup--text\"><h3 class=\"wcs-lineup__title\">Line-up<\/h3><div class=\"wcs-lineup__excerpt\"><p>Resident DJ&#039;s<\/p>\n<\/div><\/div><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Resident DJ's<\/p>\n","protected":false},"template":"","wcs-type":[1537,3815,3958,308],"dj":[],"class_list":["post-1099717","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-aftersun-boat-party","wcs-type-saturday","wcs-type-3958","wcs-type-boat-party","wcs-room-playa-den-bossa-boat-parties"],"acf":[],"_wcs_timestamp":"1784398500","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/class\/1099717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/media\/994758"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/media?parent=1099717"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/wcs-type?post=1099717"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/dj?post=1099717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}