{"id":1091664,"date":"2026-01-30T15:37:17","date_gmt":"2026-01-30T15:37:17","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/our-house-hi-ibiza-2026-06-10\/"},"modified":"2026-05-13T22:00:42","modified_gmt":"2026-05-13T21:00:42","slug":"our-house-hi-ibiza-2026-06-10","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/nl\/event\/our-house-hi-ibiza-2026-06-10\/","title":{"rendered":"Our House"},"content":{"rendered":"<p>De hitproducers MEDUZA en James Hype keren terug naar H\u00ef Ibiza voor nog een explosief seizoen van Our House, waarbij ze de dinsdagavonden overnemen van 27 mei tot 30 september.<\/p>\n<p>Our House combineert stadionenergie met clubcultuur en is een high-octane ervaring waar genre-overstijgende sets, big-room anthems en next-level productie samenkomen. Verwacht back-to-back madness, verrassingsartiesten en een dansvloer vol pure elektriciteit.  Een hoogtepunt van het Ibiza 2026 seizoen.<\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Line-up<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/james-hype\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/james-hype-150x150.jpg\" alt=\"James Hype\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">James Hype<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/meduza\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/meduza-150x150.jpg\" alt=\"Meduza\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Meduza<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/nora-en-pure\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Nora En Pure\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Nora En Pure<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/sama\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Sama\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Sama<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/zamna-sound-system\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Zamna Sound System\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Zamna Sound System<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/henri-bergman\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Henri Bergman\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Henri Bergman<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/friends\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"&amp;Friends\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">&amp;Friends<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/andro\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Andro\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Andro<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/laherte\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Laherte\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Laherte<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>James Hype<br \/>\nMeduza\u00b3<br \/>\nNora En Pure<br \/>\nSama<br \/>\nClub Room &#8211; Offweek<br \/>\nZamna Sound System<br \/>\nHenri Bergman<br \/>\n&amp;Friends<br \/>\nAndro B2B Laherte<\/p>\n","protected":false},"template":"","wcs-type":[3812,3958,307,2237],"dj":[14836,5326,5327,12722,12723,13731,14806,14834,14835],"class_list":["post-1091664","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-wednesday","wcs-type-3958","wcs-type-superclub","wcs-type-our-house","wcs-room-hi-ibiza","dj-laherte","dj-james-hype","dj-meduza","dj-nora-en-pure","dj-sama","dj-friends","dj-zamna-sound-system","dj-henri-bergman","dj-andro"],"acf":[],"_wcs_timestamp":"1781132340","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/class\/1091664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/media\/1083049"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/media?parent=1091664"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/wcs-type?post=1091664"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/dj?post=1091664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}