{"id":1091227,"date":"2026-01-30T15:39:33","date_gmt":"2026-01-30T15:39:33","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/joseph-capriati-presents-metamorfosi-amnesia-2026-07-28\/"},"modified":"2026-04-27T15:59:43","modified_gmt":"2026-04-27T14:59:43","slug":"joseph-capriati-presents-metamorfosi-amnesia-2026-07-28","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/nl\/event\/joseph-capriati-presents-metamorfosi-amnesia-2026-07-28\/","title":{"rendered":"Joseph Capriati Presenteert Metamorfosi"},"content":{"rendered":"<p>Techno-titan Joseph Capriati brengt zijn transformerende feestconcept Metamorfosi terug naar Amnesia voor de zomer van 2026. Elke dinsdag van 30 juni tot 29 september biedt deze gedurfde residentie hoogwaardige line-ups en emotioneel geladen sets in beide zalen van de club. <\/p>\n<p>Metamorfosi, bekend om zijn artistieke visie en muzikale diepgang, is een sonische evolutie geworteld in Capriati&#8217;s Napolitaanse spirit, die dansers uitnodigt tot een staat van verandering, energie en verbinding.<\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Line-up<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/joseph-capriati\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/joseph-capriati-150x150.jpg\" alt=\"Joseph Capriati\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Joseph Capriati<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/damian-lazarus\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Damian Lazarus\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Damian Lazarus<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/chelina-manuhutu\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Chelina Manuhutu\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Chelina Manuhutu<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/stacey-pullen\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Stacey Pullen\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Stacey Pullen<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/baggi\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Baggi\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Baggi<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/yanamaste\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Yanamaste\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Yanamaste<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/adiel\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Adiel\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Adiel<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/jakojako\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"JakoJako\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">JakoJako<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/luigi-madonna\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Luigi Madonna\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Luigi Madonna<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Joseph Capriati<br \/>\nDamian Lazarus<br \/>\nChelina Manuhutu<br \/>\nStacey Pullen<br \/>\nBaggi<br \/>\nYanamaste<br \/>\nAdiel<br \/>\nJakoJako<br \/>\nLuigi Madonna<\/p>\n","protected":false},"template":"","wcs-type":[307,2916,3811,3958],"dj":[4403,4714,9355,12798,12828,12970,12971,12972,12973],"class_list":["post-1091227","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-superclub","wcs-type-joseph-capriati-presents-metamorfosi","wcs-type-tuesday","wcs-type-3958","wcs-room-amnesia","dj-joseph-capriati","dj-chelina-manuhutu","dj-damian-lazarus","dj-adiel","dj-yanamaste","dj-stacey-pullen","dj-luigi-madonna","dj-baggi","dj-jakojako"],"acf":[],"_wcs_timestamp":"1785279540","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/class\/1091227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/media\/1107158"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/media?parent=1091227"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/wcs-type?post=1091227"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/dj?post=1091227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}