{"id":1006457,"date":"2025-11-25T14:25:23","date_gmt":"2025-11-25T14:25:23","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/pool-party-o-beach-2026-08-21\/"},"modified":"2026-04-02T11:47:23","modified_gmt":"2026-04-02T10:47:23","slug":"pool-party-o-beach-2026-08-21","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/nl\/event\/pool-party-o-beach-2026-08-21\/","title":{"rendered":"Pool Party"},"content":{"rendered":"<p>Vrijdag is een viering van vrijheid. <\/p>\n<p>Freaks, unieke personen en vrije geesten nemen het zwembad over voor O Beach&#8217;s meest gedurfde feest. Met opbeurende house, live artiesten en een volledig spectrum aan kleur en creativiteit, is de Pool Party de plek waar zelfexpressie heerst.  <\/p>\n<p>Kom zoals je bent. Alle vibes zijn welkom. O Beach feest niet alleen.   Ze SPELEN ALLEMAAL \u2014 DE HELE DAG.<\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Line-up<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/dj-cameo\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/cameo-150x150.jpg\" alt=\"DJ Cameo\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">DJ Cameo<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/jamie-love\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/jamie-love-150x150.jpg\" alt=\"Jamie Love\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Jamie Love<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/lucy-jane\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Lucy Jane\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Lucy Jane<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/parris-taylor\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Parris Taylor\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Parris Taylor<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/sam-dungate\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/sun-dungate-150x150.jpg\" alt=\"Sam Dungate\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Sam Dungate<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/juliet-thurbz\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Juliet Thurbz\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Juliet Thurbz<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/nl\/dj\/albert-bace-live-percussie\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Albert Bace (live percussie)\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Albert Bace (live percussie)<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>DJ Cameo<br \/>\nJamie Love<br \/>\nLucy Jane<br \/>\nParris Taylor<br \/>\nSam Dungate<br \/>\nJuliet Thurbz<br \/>\nAlbert Bace (live percussie)<\/p>\n","protected":false},"template":"","wcs-type":[3814,3958,195],"dj":[4594,11309,4531,4570,4571,4592,4593],"class_list":["post-1006457","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-friday","wcs-type-3958","wcs-type-pool-party","wcs-room-o-beach","dj-albert-bace-live-percussie","dj-juliet-thurbz","dj-jamie-love","dj-lucy-jane","dj-parris-taylor","dj-sam-dungate","dj-dj-cameo"],"acf":[],"_wcs_timestamp":"1787317200","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/class\/1006457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/media\/994035"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/media?parent=1006457"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/wcs-type?post=1006457"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/nl\/wp-json\/wp\/v2\/dj?post=1006457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}