{"id":5601,"count":10,"description":"I Gorgon City, composti dai DJ inglesi Kye \"Foamo\" Gibbon e Matt \"RackNRuin\" Robson-Scott, sono noti per la loro coinvolgente musica house e le loro energiche esibizioni dal vivo. Con successi come \"Ready For Your Love\" e \"Real Life\", sono diventati un punto fermo nella scena della musica dance. La loro residency a Ibiza all'Amnesia e le frequenti apparizioni nei migliori club di tutto il mondo hanno consolidato il loro status di top DJ.  ","link":"https:\/\/ticketsibiza.com\/it\/dj\/gorgon-city\/","name":"Gorgon City","slug":"gorgon-city","taxonomy":"dj","meta":[],"acf":{"dj_image":null,"featured_dj":false},"uncode_term_thumbnail_id":"585305","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/dj\/5601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/dj"}],"about":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/taxonomies\/dj"}],"wp:post_type":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class?dj=5601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}