{"id":1150707,"date":"2026-04-23T17:34:21","date_gmt":"2026-04-23T16:34:21","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/j-balvin-dj-snake-ushuaia-2026-06-14\/"},"modified":"2026-04-23T17:34:21","modified_gmt":"2026-04-23T16:34:21","slug":"j-balvin-dj-snake-ushuaia-2026-06-14","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/it\/event\/j-balvin-dj-snake-ushuaia-2026-06-14\/","title":{"rendered":"J Balvin &amp; DJ Snake"},"content":{"rendered":"<p>J Balvin e DJ Snake portano il loro show congiunto a Ushua\u00efa per due date a giugno 2026, un abbinamento che unisce la pi\u00f9 grande star del reggaeton dell\u2019ultimo decennio con il produttore francese dietro alcuni dei brani crossover pi\u00f9 ascoltati degli anni 2010 e 2020. Il palco principale all\u2019aperto di Ushua\u00efa \u00e8 progettato appositamente per show di questa portata: produzione completa, enormi schermi LED e una programmazione dal tramonto alla notte che funziona perfettamente con reggaeton, Latin house ed elettronica pop da festival. Aspettati i pi\u00f9 grandi successi dai cataloghi di entrambi gli artisti, mashup crossover e la folla di Platja d\u2019en Bossa a tutto volume. Due date, due serate in alta stagione e un evento Latin-meets-electronic che non ha equivalenti sull\u2019isola quest\u2019estate.   <\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Lineup<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/it\/dj\/j-balvin\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"J Balvin\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">J Balvin<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/it\/dj\/dj-snake\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"DJ Snake\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">DJ Snake<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>J Balvin<br \/>\nDJ Snake<\/p>\n","protected":false},"template":"","wcs-type":[3816,3958,12594,307],"dj":[12600,12601],"class_list":["post-1150707","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-sunday","wcs-type-3958","wcs-type-j-balvin-dj-snake","wcs-type-superclub","wcs-room-ushuaia","dj-j-balvin","dj-dj-snake"],"acf":[],"_wcs_timestamp":"1781456400","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class\/1150707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media\/1089199"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media?parent=1150707"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/wcs-type?post=1150707"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/dj?post=1150707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}