{"id":1148573,"date":"2026-04-23T17:38:59","date_gmt":"2026-04-23T16:38:59","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/la-troya-chinois-2026-08-24\/"},"modified":"2026-04-23T17:38:59","modified_gmt":"2026-04-23T16:38:59","slug":"la-troya-chinois-2026-08-24","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/it\/event\/la-troya-chinois-2026-08-24\/","title":{"rendered":"La Troya"},"content":{"rendered":"<p>La Troya torna al Chinois ogni luned\u00ec da fine maggio a inizio ottobre 2026, portando avanti una delle istituzioni pi\u00f9 longeve nella storia del clubbing di Ibiza. Nata originariamente all\u2019Amnesia alla fine degli anni Novanta, La Troya \u00e8 da sempre la serata pi\u00f9 teatrale, inclusiva e spudoratamente camp dell\u2019isola, con un pubblico che spazia dalla scena LGBTQ+ ai raver della vecchia scuola, fino ai neofiti attratti dallo spettacolo. Il passaggio al Chinois offre alla festa un ambiente pi\u00f9 piccolo e intimo, con il caratteristico format del locale che unisce cena panasiatica e clubbing dopocena. Aspettati disco, tech house e classici inni vocali suonati a tutto volume, ballerini, drag performer e un pubblico che ama travestirsi. I luned\u00ec a Ibiza appartengono a La Troya, e lo sono ormai da molto tempo.    <\/p>\n<div class=\"wcs-lineup wcs-lineup--text\"><h3 class=\"wcs-lineup__title\">Lineup<\/h3><div class=\"wcs-lineup__excerpt\"><p>Line up da annunciare<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Line up da annunciare<\/p>\n","protected":false},"template":"","wcs-type":[241,3810,3958],"dj":[],"class_list":["post-1148573","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-la-troya","wcs-type-monday","wcs-type-3958","wcs-room-chinois"],"acf":[],"_wcs_timestamp":"1787614200","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class\/1148573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media\/608442"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media?parent=1148573"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/wcs-type?post=1148573"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/dj?post=1148573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}