{"id":1147864,"date":"2026-04-23T17:35:22","date_gmt":"2026-04-23T16:35:22","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/kodo-lio-2026-07-11\/"},"modified":"2026-04-23T17:35:22","modified_gmt":"2026-04-23T16:35:22","slug":"kodo-lio-2026-07-11","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/it\/event\/kodo-lio-2026-07-11\/","title":{"rendered":"Kodo"},"content":{"rendered":"<p>Kodo conquista il sabato sera del L\u00edo da maggio a inizio ottobre 2026, segnando la residency del sabato pi\u00f9 longeva mai programmata dal locale. La serata fonde afro-house, organic house e ritmi melodici con l\u2019intera produzione cabaret del L\u00edo: ballerini, percussioni e performance dal vivo si intrecciano in lunghi DJ set. Il sabato al L\u00edo attira un pubblico internazionale variegato, felice di esplorare sonorit\u00e0 pi\u00f9 profonde rispetto a quelle dei grandi superclub, e Kodo ha costruito il suo seguito proprio su questa filosofia. Aspettati una rotazione di ospiti dal mondo dell\u2019afro e dell\u2019organic house insieme al team di DJ resident per tutte le 21 settimane. La terrazza affacciata sul porto e il format che trasforma una cena tarda in serata clubbing fanno sentire Kodo pi\u00f9 come una lunga festa tra amici che come una classica notte in discoteca. Una valida alternativa quando cerchi l\u2019energia del sabato senza le dimensioni colossali di Playa d\u2019en Bossa.     <\/p>\n<div class=\"wcs-lineup wcs-lineup--text\"><h3 class=\"wcs-lineup__title\">Lineup<\/h3><div class=\"wcs-lineup__excerpt\"><p>Line up da annunciare<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Line up da annunciare<\/p>\n","protected":false},"template":"","wcs-type":[3815,3958,12597],"dj":[],"class_list":["post-1147864","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-saturday","wcs-type-3958","wcs-type-kodo","wcs-room-lio"],"acf":[],"_wcs_timestamp":"1783814100","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class\/1147864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media\/583308"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media?parent=1147864"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/wcs-type?post=1147864"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/dj?post=1147864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}