{"id":1136960,"date":"2026-03-30T13:08:10","date_gmt":"2026-03-30T12:08:10","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/puro-reggaeton-es-paradis-2026-05-01\/"},"modified":"2026-03-30T13:08:10","modified_gmt":"2026-03-30T12:08:10","slug":"puro-reggaeton-es-paradis-2026-05-01","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/it\/event\/puro-reggaeton-es-paradis-2026-05-01\/","title":{"rendered":"Puro Reggaeton"},"content":{"rendered":"<p>Puro Reggaeton offre esattamente ci\u00f2 che promette il nome: un\u2019intera notte di reggaeton, ritmi latini e musica urban all\u2019Es Paradis ogni venerd\u00ec. In programma da fine aprile fino a fine ottobre, soddisfa la crescente richiesta di serate influenzate dai ritmi latini sull\u2019isola. Il party attira un pubblico giovane ed energico alla ricerca di qualcosa di diverso dalle tipiche offerte house e techno del resto di Ibiza.  <\/p>\n<div class=\"wcs-lineup wcs-lineup--text\"><h3 class=\"wcs-lineup__title\">Lineup<\/h3><div class=\"wcs-lineup__excerpt\"><p>Line up da annunciare<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Line up da annunciare<\/p>\n","protected":false},"template":"","wcs-type":[3814,3957,3958],"dj":[],"class_list":["post-1136960","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-friday","wcs-type-puro-reggaeton","wcs-type-3958","wcs-room-es-paradis"],"acf":[],"_wcs_timestamp":"1777672800","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class\/1136960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media\/473534"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media?parent=1136960"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/wcs-type?post=1136960"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/dj?post=1136960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}