{"id":1122592,"date":"2026-03-09T14:43:33","date_gmt":"2026-03-09T14:43:33","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/mau-p-presents-baddest-behaviour-opening-party-pacha-2026-08-05\/"},"modified":"2026-03-09T14:43:33","modified_gmt":"2026-03-09T14:43:33","slug":"mau-p-presents-baddest-behaviour-opening-party-pacha-2026-08-05","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/it\/event\/mau-p-presents-baddest-behaviour-opening-party-pacha-2026-08-05\/","title":{"rendered":"Mau P presenta Baddest Behaviour Opening Party"},"content":{"rendered":"<p>Mau P porta Baddest Behaviour al Pacha per una serie di appuntamenti del mercoled\u00ec sera da agosto a ottobre. Il produttore belga ha scalato rapidamente le classifiche con il suo sound energico e d\u2019ispirazione rave che fonde techno da ore di punta con hook contagiosi. I suoi brani sono diventati veri e propri inni dei festival e questa residency infrasettimanale al Pacha gli offre il palcoscenico ideale per sprigionare tutta quell\u2019energia in un club. Preparati a una pista da ballo fatta apposta per scatenarsi.   <\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Lineup<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/it\/dj\/mau-p\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Mau P\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Mau P<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mau P<br \/>\nAltri artisti da annunciare<\/p>\n","protected":false},"template":"","wcs-type":[334,3812,3958,8870,307],"dj":[6692],"class_list":["post-1122592","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-opening-party","wcs-type-wednesday","wcs-type-3958","wcs-type-mau-p-presents-baddest-behaviour","wcs-type-superclub","wcs-room-pacha","dj-mau-p"],"acf":[],"_wcs_timestamp":"1785970740","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class\/1122592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media\/1065994"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media?parent=1122592"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/wcs-type?post=1122592"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/dj?post=1122592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}