{"id":1111788,"date":"2026-02-05T16:34:30","date_gmt":"2026-02-05T16:34:30","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/ibiza-anthems-pool-party-ibiza-rocks-2026-09-12\/"},"modified":"2026-03-25T19:14:42","modified_gmt":"2026-03-25T19:14:42","slug":"ibiza-anthems-pool-party-ibiza-rocks-2026-09-12","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/it\/event\/ibiza-anthems-pool-party-ibiza-rocks-2026-09-12\/","title":{"rendered":"Ibiza Anthems Pool Party"},"content":{"rendered":"<p>Ibiza Anthems torna all\u2019Ibiza Rocks Pool Club ogni sabato nel 2026, portando la colonna sonora definitiva per il tuo weekend a bordo piscina.<\/p>\n<p>Dalla House e Disco baciate dal sole, al Garage nostalgico, al Pop euforico e ai successi da club senza tempo, questa \u00e8 la musica che definisce l\u2019isola. Che si tratti di un classico degli anni \u201990 o di un inno attuale, ogni melodia colpisce con quell\u2019inconfondibile spirito delle Baleari. <\/p>\n<p>Reimmaginato per il nuovo look di Ibiza Rocks, il party settimanale fonde energia nostalgica con vibrazioni da carnevale, artisti dal vivo e una folla che sa come festeggiare. Preparati a cantare a squarciagola, ballare sfrenatamente e vivere il sogno di Ibiza. <\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Lineup<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/it\/dj\/switch-disco\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Switch Disco\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Switch Disco<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Switch Disco<br \/>\nAltri TBA<\/p>\n","protected":false},"template":"","wcs-type":[3958,8383,195,3815],"dj":[10210],"class_list":["post-1111788","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-3958","wcs-type-ibiza-anthems-pool-party","wcs-type-pool-party","wcs-type-saturday","wcs-room-ibiza-rocks","dj-switch-disco"],"acf":[],"_wcs_timestamp":"1789228800","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class\/1111788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media\/1107166"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media?parent=1111788"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/wcs-type?post=1111788"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/dj?post=1111788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}