{"id":1108644,"date":"2026-02-05T16:15:57","date_gmt":"2026-02-05T16:15:57","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/lovejuice-o-beach-2026-08-16\/"},"modified":"2026-05-28T09:47:47","modified_gmt":"2026-05-28T08:47:47","slug":"lovejuice-o-beach-2026-08-16","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/it\/event\/lovejuice-o-beach-2026-08-16\/","title":{"rendered":"LoveJuice"},"content":{"rendered":"<p>Il fenomeno globale LoveJuice sbarca all\u2019O Beach Ibiza per la prima volta in assoluto nel 2026 con cinque date esclusive all\u2019insegna della pura house music feel-good. Conosciuto per la sua atmosfera vibrante e una produzione di livello mondiale, LoveJuice \u00e8 diventato il brand di riferimento per i party da Marbella a Dubai, e ora porta la sua energia ineguagliabile sull\u2019Isola Bianca.<\/p>\n<p>Aspettati vibrazioni positive, ritmi baciati dal sole e un dancefloor pieno di bella gente che celebra la vita a bordo piscina. Non perdere l\u2019occasione di vivere il party votato come il pool party n. 1 al mondo, finalmente a Ibiza. Lascia scorrere il LoveJuice!<\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Lineup<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/it\/dj\/sammy-porter\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Sammy Porter\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Sammy Porter<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/it\/dj\/george-mensah\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"George Mensah\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">George Mensah<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/it\/dj\/becca-b\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Becca B\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Becca B<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/it\/dj\/act-on\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Act On\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Act On<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sammy Porter<br \/>\nGeorge Mensah<br \/>\nBecca B<br \/>\nAct On<\/p>\n","protected":false},"template":"","wcs-type":[195,2946,3816,3958],"dj":[15655,15656,15640,15642],"class_list":["post-1108644","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-pool-party","wcs-type-lovejuice","wcs-type-sunday","wcs-type-3958","wcs-room-o-beach","dj-becca-b","dj-act-on","dj-george-mensah","dj-sammy-porter"],"acf":[],"_wcs_timestamp":"1786885200","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class\/1108644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media\/993750"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media?parent=1108644"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/wcs-type?post=1108644"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/dj?post=1108644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}