{"id":1097459,"date":"2026-02-03T11:40:46","date_gmt":"2026-02-03T11:40:46","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/aftersun-boat-party-playa-den-bossa-boat-parties-2026-06-23\/"},"modified":"2026-02-05T10:09:29","modified_gmt":"2026-02-05T10:09:29","slug":"aftersun-boat-party-playa-den-bossa-boat-parties-2026-06-23","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/it\/event\/aftersun-boat-party-playa-den-bossa-boat-parties-2026-06-23\/","title":{"rendered":"Aftersun Boat Party"},"content":{"rendered":"<p>Aftersun torna nel 2026 ed \u00e8 ancora la nuova Boat Party \/ Festa in Barca pi\u00f9 in voga di Ibiza <\/p>\n<p>Unisciti a pi\u00f9 di 300 amanti delle feste per una crociera al tramonto all-inclusive che non dimenticherai, salpando da Playa d\u2019en Bossa fino a sei volte a settimana per tutta l\u2019estate.<\/p>\n<p>Aspettati vibrazioni non-stop con musica incredibile, open bar di birra e sangria, una rinfrescante sosta per nuotare e posti in prima fila per l\u2019iconico tramonto di Ibiza, il tutto con una folla vivace ed energia imbattibile.<\/p>\n<p>I biglietti sono disponibili solo online: assicurati il tuo ora prima che spariscano!<\/p>\n<h4><div class=\"wcs-lineup wcs-lineup--text\"><h3 class=\"wcs-lineup__title\">Lineup<\/h3><div class=\"wcs-lineup__excerpt\"><p>DJ Resident<\/p>\n<\/div><\/div><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>DJ Resident<\/p>\n","protected":false},"template":"","wcs-type":[3811,3958,308,1537],"dj":[],"class_list":["post-1097459","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-tuesday","wcs-type-3958","wcs-type-boat-party","wcs-type-aftersun-boat-party","wcs-room-playa-den-bossa-boat-parties"],"acf":[],"_wcs_timestamp":"1782238500","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class\/1097459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media\/994207"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media?parent=1097459"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/wcs-type?post=1097459"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/dj?post=1097459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}