{"id":1096445,"date":"2026-02-03T11:30:08","date_gmt":"2026-02-03T11:30:08","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/ibiza-boat-club-playa-den-bossa-boat-parties-2026-08-28\/"},"modified":"2026-02-05T09:57:07","modified_gmt":"2026-02-05T09:57:07","slug":"ibiza-boat-club-playa-den-bossa-boat-parties-2026-08-28","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/it\/event\/ibiza-boat-club-playa-den-bossa-boat-parties-2026-08-28\/","title":{"rendered":"Ibiza Boat Club"},"content":{"rendered":"<p>Puoi smettere di cercare: questa \u00e8 la Boat Party \/ Festa in Barca di Ibiza che stavi aspettando nel 2026.<\/p>\n<p>L\u2019Ibiza Boat Club Five Star Boat Party ha tutto: \u00e8 un\u2019esperienza VIP per tutti gli ospiti a bordo. Come possiamo descriverla?  Beh, ti sentirai come se fossi nel tuo Beach Club personale in mezzo al mare. <\/p>\n<p>Le bevande scorreranno a fiumi, i ritmi saranno a tutto volume sul loro soundsystem VOID e sarai con altri 100 ospiti che alzeranno le mani al cielo durante il viaggio di 3 ore.<\/p>\n<p>Scegli tra birre illimitate, Sangria e Cava mentre ammiri la splendida costa di Ibiza.<\/p>\n<p>C\u2019\u00e8 anche del cibo da gustare: Paella per tutti? E avrai anche l\u2019opportunit\u00e0 di tuffarti in mare e giocare con i giochi acquatici. <\/p>\n<p>L\u2019Ibiza Boat Club salpa da Playa d\u2019en Bossa in diversi giorni durante ogni settimana della stagione. <\/p>\n<p>Come puoi immaginare, siamo grandi fan. Non a caso \u00e8 la nostra Boat Party \/ Festa in Barca numero 1 consigliata a Ibiza.  Inoltre, ha ricevuto il premio Traveler Choice di Tripadvisor la scorsa stagione.<br \/>\nCosa stai aspettando? Ci vediamo a bordo!<\/p>\n<h4><div class=\"wcs-lineup wcs-lineup--text\"><h3 class=\"wcs-lineup__title\">Lineup<\/h3><div class=\"wcs-lineup__excerpt\"><p>DJ Resident<\/p>\n<\/div><\/div><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>DJ Resident<\/p>\n","protected":false},"template":"","wcs-type":[3814,3958,308,1453],"dj":[],"class_list":["post-1096445","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-friday","wcs-type-3958","wcs-type-boat-party","wcs-type-ibiza-boat-club","wcs-room-playa-den-bossa-boat-parties"],"acf":[],"_wcs_timestamp":"1787922000","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class\/1096445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media\/994202"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media?parent=1096445"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/wcs-type?post=1096445"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/dj?post=1096445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}