{"id":1092849,"date":"2026-02-02T21:03:13","date_gmt":"2026-02-02T21:03:13","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/ibiza-rocks-pool-party-ibiza-rocks-2026-05-05\/"},"modified":"2026-02-04T15:53:44","modified_gmt":"2026-02-04T15:53:44","slug":"ibiza-rocks-pool-party-ibiza-rocks-2026-05-05","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/it\/event\/ibiza-rocks-pool-party-ibiza-rocks-2026-05-05\/","title":{"rendered":"Ibiza Rocks Pool Party"},"content":{"rendered":"<p>L\u2019originale sessione a bordo piscina, dal giorno alla notte, \u00e8 tornata pi\u00f9 forte che mai. Ogni marted\u00ec all\u2019Ibiza Rocks, l\u2019Ibiza Rocks Pool Party porta l\u2019energia con musica non-stop, MC dal vivo, ballerini, gonfiabili e una folla imbattibile. Aspettati grandi successi, vibrazioni senza compromessi e momenti da protagonista sulla pista da ballo pi\u00f9 iconica dell\u2019isola: la piscina. Prendi la tua crew, tuffati e che il caos abbia inizio.   <\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Lineup<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/it\/dj\/dj-di-ibiza-rocks\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"DJ di Ibiza Rocks\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">DJ di Ibiza Rocks<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>DJ di Ibiza Rocks<\/p>\n","protected":false},"template":"","wcs-type":[2463,3811,3958,195],"dj":[8317],"class_list":["post-1092849","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-ibiza-rocks-pool-party","wcs-type-tuesday","wcs-type-3958","wcs-type-pool-party","wcs-room-ibiza-rocks","dj-dj-di-ibiza-rocks"],"acf":[],"_wcs_timestamp":"1777996800","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class\/1092849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media\/1107166"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media?parent=1092849"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/wcs-type?post=1092849"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/dj?post=1092849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}