{"id":1092341,"date":"2026-01-30T15:40:18","date_gmt":"2026-01-30T15:40:18","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/joseph-capriati-presents-metamorfosi-amnesia-2026-09-15\/"},"modified":"2026-04-27T16:15:24","modified_gmt":"2026-04-27T15:15:24","slug":"joseph-capriati-presents-metamorfosi-amnesia-2026-09-15","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/it\/event\/joseph-capriati-presents-metamorfosi-amnesia-2026-09-15\/","title":{"rendered":"Joseph Capriati presenta Metamorfosi"},"content":{"rendered":"<p>Il titano della techno Joseph Capriati riporta il suo party concept trasformativo Metamorfosi all\u2019Amnesia per l\u2019estate 2026. In programma ogni marted\u00ec dal 30 giugno al 29 settembre, questa audace residency offre lineup di alto livello e set carichi di emozioni in entrambe le sale del club. <\/p>\n<p>Rinomato per la sua visione artistica e la profondit\u00e0 musicale, Metamorfosi \u00e8 un\u2019evoluzione sonora radicata nello spirito napoletano di Capriati, che invita i ballerini in uno stato di cambiamento, energia e connessione.<\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Lineup<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/it\/dj\/joseph-capriati\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/joseph-capriati-150x150.jpg\" alt=\"Joseph Capriati\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Joseph Capriati<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/it\/dj\/richie-hawtin\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Richie Hawtin\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Richie Hawtin<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/it\/dj\/toman\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Toman\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Toman<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/it\/dj\/paramida\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Paramida\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Paramida<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/it\/dj\/vanee\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Vanee\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Vanee<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/it\/dj\/yanamaste\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Yanamaste\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Yanamaste<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/it\/dj\/adiel\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Adiel\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Adiel<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/it\/dj\/alarico\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Alarico\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Alarico<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/it\/dj\/nuke\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Nuke\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Nuke<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Joseph Capriati<br \/>\nRichie Hawtin<br \/>\nToman<br \/>\nParamida<br \/>\nVanee<br \/>\nYanamaste<br \/>\nAdiel<br \/>\nAlarico<br \/>\nNuke<\/p>\n","protected":false},"template":"","wcs-type":[307,2916,3811,3958],"dj":[10815,12779,12783,12845,12996,13291,4425,6184,6884],"class_list":["post-1092341","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-superclub","wcs-type-joseph-capriati-presents-metamorfosi","wcs-type-tuesday","wcs-type-3958","wcs-room-amnesia","dj-paramida","dj-adiel","dj-richie-hawtin","dj-yanamaste","dj-alarico","dj-nuke","dj-joseph-capriati","dj-toman","dj-vanee"],"acf":[],"_wcs_timestamp":"1789513140","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class\/1092341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media\/1107161"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media?parent=1092341"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/wcs-type?post=1092341"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/dj?post=1092341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}