{"id":1084191,"date":"2025-09-03T00:00:00","date_gmt":"2025-09-02T23:00:00","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/baddest-behaviour-pacha-2025-09-03\/"},"modified":"2025-09-03T00:00:00","modified_gmt":"2025-09-02T23:00:00","slug":"baddest-behaviour-pacha-2025-09-03","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/it\/event\/baddest-behaviour-pacha-2025-09-03\/","title":{"rendered":"Baddest Behaviour"},"content":{"rendered":"<p>Mau P intraprende la sua prima residency al Pacha nel 2025!<\/p>\n<p>Preparati per Bad Behaviour. Mau P sar\u00e0 affiancato dai migliori DJ della scena house, che ti accompagneranno in un viaggio musicale nel club pi\u00f9 iconico di Ibiza. <\/p>\n<p>Unisciti a Mau P al Pacha ogni mercoled\u00ec da agosto a ottobre 2025.<\/p>\n<h4><span style=\"text-decoration: underline;\">Lineup<\/span><\/h4>\n<p>Mau P<br \/>\nThe Blessed Madonna<br \/>\nQuest<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mau P<br \/>\nThe Blessed Madonna<br \/>\nQuest<\/p>\n","protected":false},"template":"","wcs-type":[307,2907,2927,3812],"dj":[4809,6110,6692],"class_list":["post-1084191","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-superclub","wcs-type-2907","wcs-type-baddest-behaviour","wcs-type-wednesday","wcs-room-pacha","dj-quest","dj-the-blessed-madonna","dj-mau-p"],"acf":[],"_wcs_timestamp":"1756940340","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class\/1084191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media\/605896"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media?parent=1084191"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/wcs-type?post=1084191"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/dj?post=1084191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}