{"id":1077761,"date":"2026-01-20T17:20:47","date_gmt":"2026-01-20T17:20:47","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/float-your-boat-san-antonio-boat-parties-2026-09-05\/"},"modified":"2026-02-05T08:41:05","modified_gmt":"2026-02-05T08:41:05","slug":"float-your-boat-san-antonio-boat-parties-2026-09-05","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/it\/event\/float-your-boat-san-antonio-boat-parties-2026-09-05\/","title":{"rendered":"Float your boat"},"content":{"rendered":"<p>Preparati per l\u2019iconica esperienza del tramonto di Ibiza: Float Your Boat \u00e8 tornata per il 2026!<\/p>\n<p>Riconosciuta come una delle migliori feste al tramonto dell\u2019isola, Float Your Boat presenta i migliori DJ che suonano i migliori ritmi di Ibiza. Raduna la tua squadra e unisciti alla festa ogni marted\u00ec e sabato mentre la FYB Sunset Party Cruise salpa da San Antonio per un viaggio musicale di tre ore e mezza lungo la splendida costa occidentale di Ibiza. <\/p>\n<p>Float Your Boat non \u00e8 solo una festa, \u00e8 un\u2019esperienza sensoriale completa, che fonde Chill Out, Balearic House, classici dei club di Ibiza e nuove hit da dancefloor. Immergiti nelle epiche viste del tramonto e tuffati nelle acque turchesi con una sosta per nuotare in una delle calette nascoste di Ibiza. <\/p>\n<p>Cosa \u00e8 incluso?<br \/>\n\u2022 Boat Party \/ Festa in Barca al tramonto di 3 ore: 18:00 \u2013 21:00<br \/>\n\u2022 DJ e intrattenimento dal vivo per la colonna sonora definitiva<br \/>\n\u2022 2 drink di benvenuto (sangria) per iniziare la tua esperienza in grande stile<\/p>\n<p>Non perdere la barca: Float Your Boat sta facendo faville a Ibiza nel 2026!<\/p>\n<h4><div class=\"wcs-lineup wcs-lineup--text\"><h3 class=\"wcs-lineup__title\">Lineup<\/h3><div class=\"wcs-lineup__excerpt\"><p>DJ Resident<\/p>\n<\/div><\/div><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>DJ Resident<\/p>\n","protected":false},"template":"","wcs-type":[167,308,3815,3958],"dj":[],"class_list":["post-1077761","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-float-your-boat","wcs-type-boat-party","wcs-type-saturday","wcs-type-3958","wcs-room-san-antonio-boat-parties"],"acf":[],"_wcs_timestamp":"1788631200","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class\/1077761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media\/994205"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media?parent=1077761"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/wcs-type?post=1077761"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/dj?post=1077761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}