{"id":1076157,"date":"2025-09-03T00:00:00","date_gmt":"2025-09-02T23:00:00","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/ibiza-boat-club-formentera-with-benefits-playa-den-bossa-boat-parties-2025-09-03\/"},"modified":"2025-09-03T00:00:00","modified_gmt":"2025-09-02T23:00:00","slug":"ibiza-boat-club-formentera-with-benefits-playa-den-bossa-boat-parties-2025-09-03","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/it\/event\/ibiza-boat-club-formentera-with-benefits-playa-den-bossa-boat-parties-2025-09-03\/","title":{"rendered":"Ibiza Boat Club Formentera con vantaggi"},"content":{"rendered":"<p>Questa non \u00e8 la solita gita in barca a Ibiza. Anzi, \u00e8 importante sottolineare che Formentera with Benefits non \u00e8 affatto una festa, ma un\u2019esperienza di lusso in barca di un\u2019intera giornata da goderti durante il tuo viaggio a Ibiza nel 2025.  <\/p>\n<p>Ammirerai la splendida isola di Formentera in tutto il suo splendore, sia via terra che via mare.<\/p>\n<p>Goditi drink illimitati all\u2019open bar. Paella da far venire l\u2019acquolina in bocca.  Soste per nuotare e 5 ore di tempo libero a Formentera. Una sessione di show cooking al tramonto. Questa esperienza ha tutto e te la godrai in stile VIP con i tuoi lettini a bordo.  <\/p>\n<h4><span style=\"text-decoration: underline;\">Line-up:<\/span><\/h4>\n<p>Musica a bordo<\/p>\n<p><strong>Acquista in anticipo i biglietti per Ibiza Boat Club Formentera with Benefits e risparmia prima di andare a Ibiza.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Musica a bordo<\/p>\n","protected":false},"template":"","wcs-type":[308,422,2907],"dj":[],"class_list":["post-1076157","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-boat-party","wcs-type-ibiza-boat-club-formentera-with-benefits","wcs-type-2907","wcs-room-playa-den-bossa-boat-parties"],"acf":[],"_wcs_timestamp":"1756895400","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class\/1076157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media\/498039"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media?parent=1076157"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/wcs-type?post=1076157"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/dj?post=1076157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}