{"id":1066049,"date":"2026-01-20T16:13:44","date_gmt":"2026-01-20T16:13:44","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/john-summit-presents-experts-only-opening-party-unvrs-2026-06-01\/"},"modified":"2026-04-16T20:33:15","modified_gmt":"2026-04-16T19:33:15","slug":"john-summit-presents-experts-only-opening-party-unvrs-2026-06-01","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/it\/event\/john-summit-presents-experts-only-opening-party-unvrs-2026-06-01\/","title":{"rendered":"John Summit Presents Experts Only Opening Party \/ Festa di Apertura"},"content":{"rendered":"<p>In un debutto ibizenco incandescente, John Summit porta il suo marchio Experts Only a [UNVRS] ogni luned\u00ec per 9 serate esplosive dal 1\u00b0 giugno al 27 luglio.<\/p>\n<p>Reduce dall\u2019headlining di festival internazionali e arene sold out, la potenza nata a Chicago arriva sull\u2019isola con la sua prima residency in assoluto. Aspettati momenti euforici, drop emotivi profondi e quella caratteristica energia di Summit mentre prende il controllo totale della Main Room di [UNVRS].<\/p>\n<p>Curata da lui stesso, la lineup metter\u00e0 in evidenza stelle emergenti e nomi di peso della label Experts Only. Questo non \u00e8 solo un party &#8211; \u00e8 un movimento. Una delle residency imperdibili dell\u2019estate 2026.<\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Lineup<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/it\/dj\/john-summit\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/john-summit-150x150.jpg\" alt=\"John Summit\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">John Summit<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/it\/dj\/max-styler\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Max Styler\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Max Styler<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/it\/dj\/ayybo\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Ayybo\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Ayybo<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/it\/dj\/cole-knight\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Cole Knight\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Cole Knight<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/it\/dj\/bender\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Bender\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Bender<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Main Room<br \/>\nJohn Summit<br \/>\nMax Styler<br \/>\nAyybo<br \/>\nCole Knight<\/p>\n<p>Wild Comet<br \/>\nBender<\/p>\n","protected":false},"template":"","wcs-type":[334,396,3810,3958,4458,307],"dj":[4459,6048,6384,11823,11828],"class_list":["post-1066049","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-opening-party","wcs-type-featured","wcs-type-monday","wcs-type-3958","wcs-type-john-summit-presents-experts-only","wcs-type-superclub","wcs-room-unvrs","dj-john-summit","dj-ayybo","dj-max-styler","dj-bender","dj-cole-knight"],"acf":[],"_wcs_timestamp":"1780354740","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class\/1066049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media\/1066064"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/media?parent=1066049"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/wcs-type?post=1066049"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/it\/wp-json\/wp\/v2\/dj?post=1066049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}