{"id":14327,"count":1,"description":"","link":"https:\/\/ticketsibiza.com\/fr\/dj\/mitch-oliver\/","name":"Mitch Oliver","slug":"mitch-oliver","taxonomy":"dj","meta":[],"acf":{"dj_image":null,"featured_dj":false},"uncode_term_thumbnail_id":"585348","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/dj\/14327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/dj"}],"about":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/taxonomies\/dj"}],"wp:post_type":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class?dj=14327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}