{"id":1148669,"date":"2026-04-23T17:39:41","date_gmt":"2026-04-23T16:39:41","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/la-troya-opening-party-chinois-2026-05-25\/"},"modified":"2026-04-23T17:39:41","modified_gmt":"2026-04-23T16:39:41","slug":"la-troya-opening-party-chinois-2026-05-25","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/fr\/event\/la-troya-opening-party-chinois-2026-05-25\/","title":{"rendered":"La Troya Opening Party \/ Soir\u00e9e d\u2019Ouverture"},"content":{"rendered":"<p>La Troya revient au Chinois tous les lundis, de fin mai \u00e0 d\u00e9but octobre 2026, perp\u00e9tuant l\u2019une des institutions festives les plus anciennes de l\u2019histoire du clubbing \u00e0 Ibiza. N\u00e9e \u00e0 l\u2019Amnesia \u00e0 la fin des ann\u00e9es 90, La Troya a toujours \u00e9t\u00e9 la soir\u00e9e la plus th\u00e9\u00e2trale, inclusive et r\u00e9solument \u00ab camp \u00bb de l\u2019\u00eele, avec un public qui r\u00e9unit la sc\u00e8ne LGBTQ+, les ravers de la vieille \u00e9cole et les novices attir\u00e9s par le spectacle. Le passage au Chinois offre \u00e0 la f\u00eate un cadre plus restreint et intimiste, avec la cuisine panasiatique embl\u00e9matique de l\u2019\u00e9tablissement et son format club apr\u00e8s le d\u00eener. Attends-toi \u00e0 de la disco, de la tech house et des hymnes vocaux classiques jou\u00e9s fort et longtemps, des danseurs, des drag-queens et un public adepte du d\u00e9guisement. \u00c0 Ibiza, les lundis appartiennent \u00e0 La Troya, et c\u2019est le cas depuis longtemps.    <\/p>\n<div class=\"wcs-lineup wcs-lineup--text\"><h3 class=\"wcs-lineup__title\">Programmation<\/h3><div class=\"wcs-lineup__excerpt\"><p>Programmation \u00e0 confirmer<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Programmation \u00e0 confirmer<\/p>\n","protected":false},"template":"","wcs-type":[241,3810,3958],"dj":[],"class_list":["post-1148669","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-la-troya","wcs-type-monday","wcs-type-3958","wcs-room-chinois"],"acf":[],"_wcs_timestamp":"1779751800","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class\/1148669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media\/608442"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media?parent=1148669"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/wcs-type?post=1148669"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/dj?post=1148669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}