{"id":1148272,"date":"2026-04-23T17:37:23","date_gmt":"2026-04-23T16:37:23","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/la-disturbia-eden-2026-08-13\/"},"modified":"2026-05-26T15:36:17","modified_gmt":"2026-05-26T14:36:17","slug":"la-disturbia-eden-2026-08-13","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/fr\/event\/la-disturbia-eden-2026-08-13\/","title":{"rendered":"La Disturbia"},"content":{"rendered":"<p>La Disturbia s\u2019empare des jeudis \u00e0 l\u2019Eden de d\u00e9but juillet \u00e0 fin ao\u00fbt 2026, pour une s\u00e9rie de huit semaines en pleine saison. La r\u00e9sidence mise sur un style tech house et tribal plus dur et percutant, se forgeant une identit\u00e9 nocturne qui se d\u00e9marque du reste de la programmation de l\u2019Eden. La Disturbia a su fid\u00e9liser son public \u00e0 travers l\u2019Espagne et \u00e0 Ibiza en misant sur l\u2019\u00e9nergie et une \u00e9quipe solide de DJ r\u00e9sidents ; le cr\u00e9neau \u00e0 l\u2019Eden lui offre d\u00e9sormais le soundsystem et l\u2019espace id\u00e9al pour cette p\u00e9riode de forte affluence. Attends-toi \u00e0 une rotation d\u2019invit\u00e9s tout au long de l\u2019\u00e9t\u00e9, avec une programmation r\u00e9solument ancr\u00e9e dans la tribal tech et la house au groove puissant. Une excellente option pour tes jeudis si tu recherches une soir\u00e9e clubbing brute et intense plut\u00f4t que sophistiqu\u00e9e.    <\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Programmation<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/david-penn\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"David Penn\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">David Penn<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/stefano-noferini\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Stefano Noferini\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Stefano Noferini<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/the-cube-guys\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"The Cube Guys\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">The Cube Guys<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/stban\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Stban\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Stban<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/don-juan\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Don Juan\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Don Juan<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>David Penn<br \/>\nStefano Noferini<br \/>\nThe Cube Guys<br \/>\nStban<br \/>\nDon Juan<\/p>\n","protected":false},"template":"","wcs-type":[3958,12602,307,3813],"dj":[4631,15319,15322,15490,15491],"class_list":["post-1148272","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-3958","wcs-type-la-disturbia","wcs-type-superclub","wcs-type-thursday","wcs-room-eden","dj-david-penn","dj-stban","dj-don-juan","dj-stefano-noferini","dj-the-cube-guys"],"acf":[],"_wcs_timestamp":"1786661940","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class\/1148272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media\/1130090"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media?parent=1148272"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/wcs-type?post=1148272"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/dj?post=1148272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}