{"id":1148176,"date":"2026-04-23T17:36:25","date_gmt":"2026-04-23T16:36:25","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/kodo-lio-2026-09-12\/"},"modified":"2026-04-23T17:36:25","modified_gmt":"2026-04-23T16:36:25","slug":"kodo-lio-2026-09-12","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/fr\/event\/kodo-lio-2026-09-12\/","title":{"rendered":"Kodo"},"content":{"rendered":"<p>Kodo s\u2019empare des samedis soirs au L\u00edo de mai \u00e0 d\u00e9but octobre 2026, la plus longue r\u00e9sidence du samedi jamais programm\u00e9e par l\u2019\u00e9tablissement. La soir\u00e9e m\u00eale Afro-house, organic house et rythmes m\u00e9lodiques \u00e0 la production compl\u00e8te du cabaret L\u00edo : danseurs, percussions et performances live s\u2019entrem\u00ealent lors de longs sets de DJ. Les samedis au L\u00edo attirent une client\u00e8le internationale vari\u00e9e, ravie d\u2019explorer des sonorit\u00e9s musicales plus profondes que dans les grands superclubs, et Kodo a su fid\u00e9liser son public autour de cet univers. Attends-toi \u00e0 une rotation d\u2019invit\u00e9s issus de la sc\u00e8ne Afro et organic house aux c\u00f4t\u00e9s de l\u2019\u00e9quipe de DJ r\u00e9sidents tout au long de ces 21 semaines. Avec sa terrasse face au port et son format passant du d\u00eener tardif au club, Kodo ressemble davantage \u00e0 une longue soir\u00e9e entre amis qu\u2019\u00e0 une simple nuit en bo\u00eete. Une excellente alternative quand tu recherches l\u2019\u00e9nergie du samedi sans la d\u00e9mesure de Playa d\u2019en Bossa.     <\/p>\n<div class=\"wcs-lineup wcs-lineup--text\"><h3 class=\"wcs-lineup__title\">Programmation<\/h3><div class=\"wcs-lineup__excerpt\"><p>Programmation \u00e0 confirmer<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Programmation \u00e0 confirmer<\/p>\n","protected":false},"template":"","wcs-type":[3958,12597,3815],"dj":[],"class_list":["post-1148176","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-3958","wcs-type-kodo","wcs-type-saturday","wcs-room-lio"],"acf":[],"_wcs_timestamp":"1789257300","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class\/1148176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media\/583308"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media?parent=1148176"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/wcs-type?post=1148176"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/dj?post=1148176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}