{"id":1147768,"date":"2026-04-23T17:35:14","date_gmt":"2026-04-23T16:35:14","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/kodo-lio-2026-07-04\/"},"modified":"2026-04-23T17:35:14","modified_gmt":"2026-04-23T16:35:14","slug":"kodo-lio-2026-07-04","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/fr\/event\/kodo-lio-2026-07-04\/","title":{"rendered":"Kodo"},"content":{"rendered":"<p>Kodo s\u2019approprie les samedis soirs au L\u00edo de mai \u00e0 d\u00e9but octobre 2026, la r\u00e9sidence du samedi la plus longue jamais programm\u00e9e par le lieu. La soir\u00e9e m\u00eale afro-house, organic house et rythmes m\u00e9lodiques, avec toute la production cabaret du L\u00edo : danseurs, percussions et performances live int\u00e9gr\u00e9es \u00e0 de longs sets de DJ. Les samedis au L\u00edo attirent un public international vari\u00e9, heureux d\u2019aller plus loin musicalement que ne le permettent les plus grands superclubs, et Kodo a construit son audience autour de cet espace. Attends-toi \u00e0 des invit\u00e9s tournants issus des sc\u00e8nes afro et organic house, aux c\u00f4t\u00e9s de l\u2019\u00e9quipe de DJ r\u00e9sidents, sur 21 semaines. La terrasse en front de port et le format d\u00eener tardif qui se transforme en club donnent \u00e0 Kodo des airs de longue soir\u00e9e entre amis plut\u00f4t que de nuit de club classique. Une alternative solide quand tu veux l\u2019\u00e9nergie du samedi sans l\u2019\u00e9chelle de Playa d\u2019en Bossa.     <\/p>\n<div class=\"wcs-lineup wcs-lineup--text\"><h3 class=\"wcs-lineup__title\">Programmation<\/h3><div class=\"wcs-lineup__excerpt\"><p>Programmation \u00e0 confirmer<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Programmation \u00e0 confirmer<\/p>\n","protected":false},"template":"","wcs-type":[3815,3958,12597],"dj":[],"class_list":["post-1147768","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-saturday","wcs-type-3958","wcs-type-kodo","wcs-room-lio"],"acf":[],"_wcs_timestamp":"1783209300","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class\/1147768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media\/583308"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media?parent=1147768"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/wcs-type?post=1147768"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/dj?post=1147768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}