{"id":1123239,"date":"2026-03-10T12:49:29","date_gmt":"2026-03-10T12:49:29","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/solid-grooves-dc10-2026-07-30\/"},"modified":"2026-05-07T14:22:07","modified_gmt":"2026-05-07T13:22:07","slug":"solid-grooves-dc10-2026-07-30","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/fr\/event\/solid-grooves-dc10-2026-07-30\/","title":{"rendered":"Solid Grooves"},"content":{"rendered":"<p>Solid Grooves revient dans sa maison spirituelle au DC10 pour une nouvelle saison de clubbing brut, sans chichis. <\/p>\n<p>Fond\u00e9e par Michael Bibi, la soir\u00e9e est devenue l\u2019une des r\u00e9sidences hebdomadaires les plus respect\u00e9es de l\u2019\u00eele, attirant un public qui vient d\u2019abord pour la musique, et le reste ensuite. Le cadre du Garden au DC10 offre une ambiance \u00e9pur\u00e9e, en plein air, qui colle parfaitement au son Solid Grooves : de la house et de la techno profondes et percutantes, sans fioritures.  <\/p>\n<p>Tous les jeudis, de juin \u00e0 octobre.<\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Programmation<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/ahmed-spins\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Ahmed Spins\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Ahmed Spins<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/dennis-cruz\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2022\/11\/dennis-cruz-150x150.png\" alt=\"Dennis Cruz\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Dennis Cruz<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/dj-sweet6teen\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"DJ Sweet6teen\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">DJ Sweet6teen<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/maz\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Maz\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Maz<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/mella-dee\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Mella Dee\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Mella Dee<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/pawsa\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2022\/09\/pawsa-150x150.jpg\" alt=\"PAWSA\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">PAWSA<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/route-94\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Route 94\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Route 94<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/the-ghost\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"The Ghost\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">The Ghost<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/toman\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Toman\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Toman<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/wheats\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Wheats\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Wheats<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ahmed Spins<br \/>\nDennis Cruz<br \/>\ndj sweet6teen<br \/>\nMaz<br \/>\nMella Dee<br \/>\nPAWSA<br \/>\nRoute 94<br \/>\nThe Ghost<br \/>\nToman<br \/>\nWheats<\/p>\n","protected":false},"template":"","wcs-type":[158,3813,3958],"dj":[6096,6145,6845,6941,7155,10837,13870,13871,5085,5617],"class_list":["post-1123239","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-solid-grooves","wcs-type-thursday","wcs-type-3958","wcs-room-dc10","dj-maz","dj-wheats","dj-dennis-cruz","dj-pawsa","dj-ahmed-spins","dj-dj-sweet6teen","dj-mella-dee","dj-the-ghost","dj-toman","dj-route-94"],"acf":[],"_wcs_timestamp":"1785430800","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class\/1123239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media\/989342"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media?parent=1123239"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/wcs-type?post=1123239"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/dj?post=1123239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}