{"id":1109401,"date":"2026-02-05T16:18:18","date_gmt":"2026-02-05T16:18:18","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/bresh-amnesia-2026-08-29\/"},"modified":"2026-02-05T16:18:18","modified_gmt":"2026-02-05T16:18:18","slug":"bresh-amnesia-2026-08-29","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/fr\/event\/bresh-amnesia-2026-08-29\/","title":{"rendered":"BRESH"},"content":{"rendered":"<p>La f\u00eate la plus color\u00e9e du monde est de retour sur l\u2019\u00cele Blanche ! BRESH revient \u00e0 Amnesia tous les samedis cet \u00e9t\u00e9, apportant son chaos de bonne humeur et sa bande sonore qui m\u00e9lange les genres sur l\u2019un des dancefloors les plus l\u00e9gendaires d\u2019Ibiza. <\/p>\n<p>Attends-toi \u00e0 un m\u00e9lange euphorique de reggaeton, pop, disco, hip hop et rock, des visuels vibrants, des bombes de fleurs, et une foule qui ne pense qu\u2019aux bonnes vibes et z\u00e9ro pr\u00e9tention. N\u00e9 \u00e0 Buenos Aires et maintenant ph\u00e9nom\u00e8ne mondial, BRESH est plus qu\u2019une f\u00eate &#8211; c\u2019est une c\u00e9l\u00e9bration de la libert\u00e9, de l\u2019amiti\u00e9 et de danser comme si personne ne regardait. Laisse pleuvoir les paillettes.  <\/p>\n<div class=\"wcs-lineup wcs-lineup--text\"><h3 class=\"wcs-lineup__title\">Programmation<\/h3><div class=\"wcs-lineup__excerpt\"><p>Programmation \u00e0 confirmer<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Programmation \u00e0 confirmer<\/p>\n","protected":false},"template":"","wcs-type":[3815,3958,307,2103],"dj":[],"class_list":["post-1109401","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-saturday","wcs-type-3958","wcs-type-superclub","wcs-type-bresh","wcs-room-amnesia"],"acf":[],"_wcs_timestamp":"1788044340","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class\/1109401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media\/1104512"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media?parent=1109401"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/wcs-type?post=1109401"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/dj?post=1109401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}