{"id":1098028,"date":"2026-02-03T11:43:25","date_gmt":"2026-02-03T11:43:25","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/aftersun-boat-party-playa-den-bossa-boat-parties-2026-07-19\/"},"modified":"2026-02-05T10:13:09","modified_gmt":"2026-02-05T10:13:09","slug":"aftersun-boat-party-playa-den-bossa-boat-parties-2026-07-19","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/fr\/event\/aftersun-boat-party-playa-den-bossa-boat-parties-2026-07-19\/","title":{"rendered":"Aftersun Boat Party"},"content":{"rendered":"<p>Aftersun est de retour pour 2026 \u2013 et c\u2019est toujours la nouvelle Boat Party \/ Soir\u00e9e Bateau la plus en vogue d\u2019Ibiza <\/p>\n<p>Rejoins plus de 300 f\u00eatards pour une croisi\u00e8re au coucher du soleil tout compris que tu n\u2019oublieras pas, au d\u00e9part de Playa d\u2019en Bossa jusqu\u2019\u00e0 six fois par semaine pendant tout l\u2019\u00e9t\u00e9.<\/p>\n<p>Attends-toi \u00e0 une ambiance non-stop avec de la musique incroyable, un open bar de bi\u00e8re et de sangria, une pause baignade rafra\u00eechissante et des places au premier rang pour le coucher de soleil embl\u00e9matique d\u2019Ibiza \u2013 le tout avec une foule anim\u00e9e et une \u00e9nergie imbattable.<\/p>\n<p>Les billets sont uniquement disponibles en ligne \u2013 r\u00e9serve les tiens d\u00e8s maintenant avant qu\u2019ils ne disparaissent&nbsp;!<\/p>\n<h4><div class=\"wcs-lineup wcs-lineup--text\"><h3 class=\"wcs-lineup__title\">Programmation<\/h3><div class=\"wcs-lineup__excerpt\"><p>DJs r\u00e9sidents<\/p>\n<\/div><\/div><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>DJs r\u00e9sidents<\/p>\n","protected":false},"template":"","wcs-type":[3816,3958,308,1537],"dj":[],"class_list":["post-1098028","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-sunday","wcs-type-3958","wcs-type-boat-party","wcs-type-aftersun-boat-party","wcs-room-playa-den-bossa-boat-parties"],"acf":[],"_wcs_timestamp":"1784484900","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class\/1098028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media\/994480"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media?parent=1098028"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/wcs-type?post=1098028"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/dj?post=1098028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}