{"id":1095053,"date":"2026-02-03T11:19:41","date_gmt":"2026-02-03T11:19:41","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/ibiza-boat-club-playa-den-bossa-boat-parties-2026-05-31\/"},"modified":"2026-02-05T09:16:08","modified_gmt":"2026-02-05T09:16:08","slug":"ibiza-boat-club-playa-den-bossa-boat-parties-2026-05-31","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/fr\/event\/ibiza-boat-club-playa-den-bossa-boat-parties-2026-05-31\/","title":{"rendered":"Ibiza Boat Club"},"content":{"rendered":"<p>Tu peux arr\u00eater de chercher maintenant : c\u2019est la Boat Party \/ Soir\u00e9e Bateau d\u2019Ibiza que tu attendais en 2026.<\/p>\n<p>L\u2019Ibiza Boat Club Five Star Boat Party a tout pour plaire : c\u2019est une exp\u00e9rience VIP pour tous les invit\u00e9s \u00e0 bord. Comment peut-on la d\u00e9crire ? Eh bien, tu auras l\u2019impression d\u2019\u00eatre dans ton propre Beach Club en mer.   <\/p>\n<p>Les boissons couleront \u00e0 flots, les beats r\u00e9sonneront sur leur syst\u00e8me de son VOID, et tu seras avec 100 autres invit\u00e9s \u00e0 lever les bras en l\u2019air pendant les 3 heures de voyage.<\/p>\n<p>Choisis parmi les bi\u00e8res, la Sangria et le Cava \u00e0 volont\u00e9 tout en admirant la magnifique c\u00f4te d\u2019Ibiza.<\/p>\n<p>Il y a aussi de quoi se r\u00e9galer : une Paella, \u00e7a te dit ? Et tu auras aussi l\u2019occasion de plonger dans la mer et de t\u2019amuser avec les jeux aquatiques. <\/p>\n<p>L\u2019Ibiza Boat Club prend le large depuis Playa d\u2019en Bossa plusieurs jours par semaine tout au long de la saison. <\/p>\n<p>Comme vous pouvez le constater, nous sommes de grands fans. Ce n\u2019est pas pour rien que c\u2019est notre Soir\u00e9e Bateau Ibiza pr\u00e9f\u00e9r\u00e9e. Elle a \u00e9galement re\u00e7u le prix Traveler Choice de Tripadvisor la saison derni\u00e8re.<br \/>\nQu\u2019attendez-vous ?   \u00c0 bient\u00f4t \u00e0 bord !<\/p>\n<h4><div class=\"wcs-lineup wcs-lineup--text\"><h3 class=\"wcs-lineup__title\">Programmation<\/h3><div class=\"wcs-lineup__excerpt\"><p>DJs r\u00e9sidents<\/p>\n<\/div><\/div><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>DJs r\u00e9sidents<\/p>\n","protected":false},"template":"","wcs-type":[3816,3958,308,1453],"dj":[],"class_list":["post-1095053","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-sunday","wcs-type-3958","wcs-type-boat-party","wcs-type-ibiza-boat-club","wcs-room-playa-den-bossa-boat-parties"],"acf":[],"_wcs_timestamp":"1780232400","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class\/1095053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media\/994475"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media?parent=1095053"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/wcs-type?post=1095053"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/dj?post=1095053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}