{"id":1092398,"date":"2026-01-30T15:39:52","date_gmt":"2026-01-30T15:39:52","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/joseph-capriati-presents-metamorfosi-amnesia-2026-08-18\/"},"modified":"2026-04-27T16:06:11","modified_gmt":"2026-04-27T15:06:11","slug":"joseph-capriati-presents-metamorfosi-amnesia-2026-08-18","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/fr\/event\/joseph-capriati-presents-metamorfosi-amnesia-2026-08-18\/","title":{"rendered":"Joseph Capriati pr\u00e9sente Metamorfosi"},"content":{"rendered":"<p>Le titan de la techno Joseph Capriati ram\u00e8ne son concept de soir\u00e9e transformatrice Metamorfosi \u00e0 Amnesia pour l\u2019\u00e9t\u00e9 2026. Se d\u00e9roulant tous les mardis du 30 juin au 29 septembre, cette r\u00e9sidence audacieuse propose des programmations de haut calibre et des sets charg\u00e9s d\u2019\u00e9motion dans les deux salles du club. <\/p>\n<p>Reconnue pour sa vision artistique et sa profondeur musicale, Metamorfosi est une \u00e9volution sonore enracin\u00e9e dans l\u2019esprit napolitain de Capriati, invitant les danseurs dans un \u00e9tat de changement, d\u2019\u00e9nergie et de connexion.<\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Programmation<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/joseph-capriati\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/joseph-capriati-150x150.jpg\" alt=\"Joseph Capriati\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Joseph Capriati<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/cloonee\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/cloonee-150x150.jpg\" alt=\"Cloonee\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Cloonee<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/traumer\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Traumer\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Traumer<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/ben-klock\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Ben Klock\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Ben Klock<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/alarico\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Alarico\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Alarico<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/serafina\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Serafina\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Serafina<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/antonio-pepe\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Antonio Pepe\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Antonio Pepe<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Joseph Capriati<br \/>\nCloonee<br \/>\nTraumer<br \/>\nBen Klock<br \/>\nAlarico<br \/>\nSerafina<br \/>\nAntonio Pepe<\/p>\n","protected":false},"template":"","wcs-type":[307,2916,3811,3958],"dj":[5029,10117,12835,12911,13000,4388,4762],"class_list":["post-1092398","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-superclub","wcs-type-joseph-capriati-presents-metamorfosi","wcs-type-tuesday","wcs-type-3958","wcs-room-amnesia","dj-cloonee","dj-traumer","dj-serafina","dj-ben-klock","dj-alarico","dj-joseph-capriati","dj-antonio-pepe"],"acf":[],"_wcs_timestamp":"1787093940","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class\/1092398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media\/1107159"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media?parent=1092398"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/wcs-type?post=1092398"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/dj?post=1092398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}