{"id":1091616,"date":"2026-01-30T15:37:30","date_gmt":"2026-01-30T15:37:30","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/our-house-hi-ibiza-2026-06-24\/"},"modified":"2026-05-13T22:00:30","modified_gmt":"2026-05-13T21:00:30","slug":"our-house-hi-ibiza-2026-06-24","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/fr\/event\/our-house-hi-ibiza-2026-06-24\/","title":{"rendered":"Our House"},"content":{"rendered":"<p>Les producteurs \u00e0 succ\u00e8s MEDUZA et James Hype reviennent \u00e0 H\u00ef Ibiza pour une nouvelle saison explosive de Our House, qui se d\u00e9roulera tous les mardis soirs du 27 mai au 30 septembre.<\/p>\n<p>M\u00ealant l\u2019\u00e9nergie d\u2019un stade \u00e0 la culture club, Our House est une exp\u00e9rience survolt\u00e9e o\u00f9 les sets d\u00e9fiant les genres, les hymnes de grande envergure et la production de niveau sup\u00e9rieur se rencontrent. Attendez-vous \u00e0 une folie incessante, \u00e0 des invit\u00e9s surprises et \u00e0 une piste de danse d\u00e9bordant d\u2019\u00e9lectricit\u00e9 pure. Un point fort de la saison Ibiza 2026.  <\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Programmation<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/james-hype\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/james-hype-150x150.jpg\" alt=\"James Hype\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">James Hype<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/meduza\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/meduza-150x150.jpg\" alt=\"Meduza\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Meduza<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/magdalena\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Magdalena\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Magdalena<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/olympe\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Olympe\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Olympe<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/alex-wann\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Alex Wann\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Alex Wann<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/joezi\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Joezi\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Joezi<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/zamna-sound-system\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Zamna Sound System\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Zamna Sound System<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/isa-roos\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Isa Roos\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Isa Roos<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>James Hype<br \/>\nMeduza\u00b3<br \/>\nMagdalena<br \/>\nOlympe<br \/>\nClub Room &#8211; Offweek<br \/>\nAlex Wann<br \/>\nJoezi<br \/>\nZamna Sound System<br \/>\nIsa Roos<\/p>\n","protected":false},"template":"","wcs-type":[3958,307,2237,3812],"dj":[5121,5230,5232,5628,10977,12850,14799,14819],"class_list":["post-1091616","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-3958","wcs-type-superclub","wcs-type-our-house","wcs-type-wednesday","wcs-room-hi-ibiza","dj-olympe","dj-james-hype","dj-meduza","dj-alex-wann","dj-joezi","dj-magdalena","dj-zamna-sound-system","dj-isa-roos"],"acf":[],"_wcs_timestamp":"1782341940","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class\/1091616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media\/1082983"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media?parent=1091616"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/wcs-type?post=1091616"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/dj?post=1091616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}