{"id":1091537,"date":"2026-01-30T15:37:49","date_gmt":"2026-01-30T15:37:49","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/our-house-hi-ibiza-2026-07-15\/"},"modified":"2026-06-26T11:32:09","modified_gmt":"2026-06-26T10:32:09","slug":"our-house-hi-ibiza-2026-07-15","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/fr\/event\/our-house-hi-ibiza-2026-07-15\/","title":{"rendered":"Our House"},"content":{"rendered":"<p>Les producteurs \u00e0 succ\u00e8s MEDUZA et James Hype reviennent \u00e0 H\u00ef Ibiza pour une nouvelle saison explosive de Our House, qui se d\u00e9roulera tous les mercredis soirs du 27 mai au 30 septembre.<\/p>\n<p>M\u00ealant l\u2019\u00e9nergie d\u2019un stade \u00e0 la culture club, Our House est une exp\u00e9rience survolt\u00e9e o\u00f9 les sets d\u00e9fiant les genres, les hymnes de grande envergure et la production de niveau sup\u00e9rieur se rencontrent. Attendez-vous \u00e0 une folie incessante, \u00e0 des invit\u00e9s surprises et \u00e0 une piste de danse d\u00e9bordant d\u2019\u00e9lectricit\u00e9 pure. Un point fort de la saison Ibiza 2026.  <\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Programmation<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/james-hype\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/james-hype-150x150.jpg\" alt=\"James Hype\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">James Hype<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/meduza\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/meduza-150x150.jpg\" alt=\"Meduza\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Meduza<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/layla-benitez\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Layla Benitez\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Layla Benitez<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/lanna\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Lanna\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Lanna<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/zamna-sound-system\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Zamna Sound System\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Zamna Sound System<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/g-pol\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"G - Pol\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">G - Pol<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/silvio-soul\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Silvio Soul\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Silvio Soul<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>James Hype<br \/>\nMeduza\u00b3<br \/>\nLayla Benitez<br \/>\nLanna<br \/>\nClub Room &#8211; Offweek<br \/>\nZamna Sound System<br \/>\nG &#8211; Pol<br \/>\nSilvio Soul<\/p>\n","protected":false},"template":"","wcs-type":[307,2237,3812,3958],"dj":[14799,14860,14861,5230,5232,12121,13023],"class_list":["post-1091537","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-superclub","wcs-type-our-house","wcs-type-wednesday","wcs-type-3958","wcs-room-hi-ibiza","dj-zamna-sound-system","dj-g-pol","dj-silvio-soul","dj-james-hype","dj-meduza","dj-layla-benitez","dj-lanna"],"acf":[],"_wcs_timestamp":"1784156340","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class\/1091537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media\/1082983"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media?parent=1091537"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/wcs-type?post=1091537"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/dj?post=1091537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}