{"id":1006541,"date":"2025-11-25T14:25:08","date_gmt":"2025-11-25T14:25:08","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/pool-party-o-beach-2026-07-17\/"},"modified":"2026-04-02T11:43:30","modified_gmt":"2026-04-02T10:43:30","slug":"pool-party-o-beach-2026-07-17","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/fr\/event\/pool-party-o-beach-2026-07-17\/","title":{"rendered":"Pool Party"},"content":{"rendered":"<p>Le vendredi est une c\u00e9l\u00e9bration de la libert\u00e9. <\/p>\n<p>Les originaux, les uniques et les esprits libres s&#8217;emparent de la piscine pour la f\u00eate la plus audacieuse d\u2019O Beach. Avec de la house euphorique, des performances live et un spectre complet de couleurs et de cr\u00e9ativit\u00e9, la Pool Party est l\u2019endroit o\u00f9 l\u2019expression de soi r\u00e8gne.  <\/p>\n<p>Viens comme tu es. Toutes les ambiances sont les bienvenues. O Beach ne fait pas que faire la f\u00eate. Ils JOUENT TOUS \u2014 TOUTE LA JOURN\u00c9E.   <\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Programmation<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/dj-cameo\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/cameo-150x150.jpg\" alt=\"DJ Cameo\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">DJ Cameo<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/jamie-love\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/jamie-love-150x150.jpg\" alt=\"Jamie Love\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Jamie Love<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/lucy-jane\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Lucy Jane\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Lucy Jane<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/parris-taylor\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Parris Taylor\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Parris Taylor<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/sam-dungate\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/sun-dungate-150x150.jpg\" alt=\"Sam Dungate\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Sam Dungate<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/juliet-thurbz\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Juliet Thurbz\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Juliet Thurbz<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/albert-bace-percussions-en-direct\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Albert Bace (percussions en direct)\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Albert Bace (percussions en direct)<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>DJ Cameo<br \/>\nJamie Love<br \/>\nLucy Jane<br \/>\nParris Taylor<br \/>\nSam Dungate<br \/>\nJuliet Thurbz<br \/>\nAlbert Bace (percussions live)<\/p>\n","protected":false},"template":"","wcs-type":[195,3814,3958],"dj":[4498,4515,4532,4603,4604,4605,11307],"class_list":["post-1006541","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-pool-party","wcs-type-friday","wcs-type-3958","wcs-room-o-beach","dj-jamie-love","dj-lucy-jane","dj-parris-taylor","dj-sam-dungate","dj-dj-cameo","dj-albert-bace-percussions-en-direct","dj-juliet-thurbz"],"acf":[],"_wcs_timestamp":"1784293200","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class\/1006541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media\/993662"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media?parent=1006541"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/wcs-type?post=1006541"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/dj?post=1006541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}