{"id":1006293,"date":"2025-11-25T14:24:31","date_gmt":"2025-11-25T14:24:31","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/o-beach-music-o-beach-2026-09-10\/"},"modified":"2026-03-25T17:53:22","modified_gmt":"2026-03-25T17:53:22","slug":"o-beach-music-o-beach-2026-09-10","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/fr\/event\/o-beach-music-o-beach-2026-09-10\/","title":{"rendered":"O Beach Music"},"content":{"rendered":"<p>Les jeudis montent le volume avec O Beach Music, la soir\u00e9e officielle du label et la derni\u00e8re nouveaut\u00e9 au calendrier d\u2019O Beach. <\/p>\n<p>Attendez-vous \u00e0 une \u00e9nergie house fra\u00eeche, \u00e0 des DJs de renom et \u00e0 des talents \u00e9mergents qui vous offriront ces hymnes de bord de piscine ensoleill\u00e9s et agr\u00e9ables. <\/p>\n<p>Votre nouveau d\u00e9but de week-end pr\u00e9f\u00e9r\u00e9, aliment\u00e9 par l\u2019ambiance imbattable d\u2019O Beach.<\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Programmation<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/weiss\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Weiss\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Weiss<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/beyond-chicago\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Beyond Chicago\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Beyond Chicago<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/bo-conquest\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Bo Conquest\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Bo Conquest<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/dj-cameo\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/cameo-150x150.jpg\" alt=\"DJ Cameo\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">DJ Cameo<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/lucy-jane\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Lucy Jane\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Lucy Jane<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Weiss<br \/>\nBeyond Chicago<br \/>\nBo Conquest<br \/>\nDJ Cameo<br \/>\nLucy Jane<\/p>\n","protected":false},"template":"","wcs-type":[3962,195,3813,3958],"dj":[4514,4515,4604,9500,9559],"class_list":["post-1006293","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-o-beach-music","wcs-type-pool-party","wcs-type-thursday","wcs-type-3958","wcs-room-o-beach","dj-beyond-chicago","dj-lucy-jane","dj-dj-cameo","dj-bo-conquest","dj-weiss"],"acf":[],"_wcs_timestamp":"1789045200","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class\/1006293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media\/993662"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media?parent=1006293"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/wcs-type?post=1006293"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/dj?post=1006293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}