{"id":1004849,"date":"2025-11-25T14:22:18","date_gmt":"2025-11-25T14:22:18","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/kisstory-o-beach-2026-06-09\/"},"modified":"2026-03-25T17:37:26","modified_gmt":"2026-03-25T17:37:26","slug":"kisstory-o-beach-2026-06-09","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/fr\/event\/kisstory-o-beach-2026-06-09\/","title":{"rendered":"Kisstory"},"content":{"rendered":"<p>Revis le pass\u00e9 tous les mardis avec KISSTORY \u00e0 O Beach Ibiza. <\/p>\n<p>Attends-toi \u00e0 une ambiance au bord de la piscine et \u00e0 de la pure nostalgie lorsque les DJ de KISS balanceront les plus grands tubes Old Skool, Garage, Hip-Hop, R&amp;B et Dance. <\/p>\n<p>Si tu sais, tu sais &#8211; c\u2019est une soir\u00e9e r\u00e9tro hebdomadaire pr\u00e9f\u00e9r\u00e9e du public o\u00f9 chaque morceau est un souvenir. C\u2019est un incontournable d\u2019Ibiza pour les amateurs de musique qui aiment l\u2019ancienne \u00e9cole. <\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Programmation<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/dj-ace\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"DJ Ace\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">DJ Ace<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/dj-cameo\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/cameo-150x150.jpg\" alt=\"DJ Cameo\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">DJ Cameo<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/lucy-jane\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Lucy Jane\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Lucy Jane<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/sam-dungate\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/sun-dungate-150x150.jpg\" alt=\"Sam Dungate\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Sam Dungate<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/fr\/dj\/albert-bace-en-live-a-la-batterie\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Albert Bace en live \u00e0 la batterie\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Albert Bace en live \u00e0 la batterie<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>DJ Ace<br \/>\nDJ Cameo<br \/>\nLucy Jane<br \/>\nSam Dungate<br \/>\nAlbert Bace en live \u00e0 la batterie<\/p>\n","protected":false},"template":"","wcs-type":[190,195,3811,3958],"dj":[9440,4515,4603,4604,9432],"class_list":["post-1004849","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-kisstory","wcs-type-pool-party","wcs-type-tuesday","wcs-type-3958","wcs-room-o-beach","dj-dj-ace","dj-lucy-jane","dj-sam-dungate","dj-dj-cameo","dj-albert-bace-en-live-a-la-batterie"],"acf":[],"_wcs_timestamp":"1781010000","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class\/1004849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media\/993662"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/media?parent=1004849"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/wcs-type?post=1004849"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/fr\/wp-json\/wp\/v2\/dj?post=1004849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}