{"id":1157235,"date":"2026-05-07T14:36:50","date_gmt":"2026-05-07T13:36:50","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/trip-chinois-2026-05-31\/"},"modified":"2026-05-07T14:36:50","modified_gmt":"2026-05-07T13:36:50","slug":"trip-chinois-2026-05-31","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/es\/event\/trip-chinois-2026-05-31\/","title":{"rendered":"VIAJE"},"content":{"rendered":"<p>TRIP es el concepto de apertura insignia de Chinois, con Seth Troxler encabezando la primer\u00edsima noche de la temporada 2026 el 2 de abril. La fiesta se celebra en varias fechas durante abril y mayo, combinando deep house y techno en el tipo de entorno \u00edntimo que las salas m\u00e1s grandes no pueden replicar. Chinois se ha posicionado como el lugar de referencia para los expertos que buscan calidad por encima del espect\u00e1culo.  <\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Cartel<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/apollonia\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Apollonia\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Apollonia<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/hugo-martinez\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Hugo Martinez\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Hugo Martinez<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/pacome\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Pacome\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Pacome<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/liana\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Liana\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Liana<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Apollonia<br \/>\nHugo Martinez<br \/>\nPacome B2B Liana<\/p>\n","protected":false},"template":"","wcs-type":[1713,3816,3958],"dj":[4073,10299,14063,14064],"class_list":["post-1157235","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-trip","wcs-type-sunday","wcs-type-3958","wcs-room-chinois","dj-apollonia","dj-hugo-martinez","dj-pacome","dj-liana"],"acf":[],"_wcs_timestamp":"1780266600","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/class\/1157235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/media\/613524"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/media?parent=1157235"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/wcs-type?post=1157235"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/dj?post=1157235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}