{"id":1157183,"date":"2026-05-07T14:37:15","date_gmt":"2026-05-07T13:37:15","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/supernova-akasha-2026-05-30\/"},"modified":"2026-05-07T14:37:15","modified_gmt":"2026-05-07T13:37:15","slug":"supernova-akasha-2026-05-30","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/es\/event\/supernova-akasha-2026-05-30\/","title":{"rendered":"Supernova"},"content":{"rendered":"<p>Supernova toma Las Dalias y su club Akasha todos los s\u00e1bados de mayo a octubre. El formato se divide en dos espacios: el jard\u00edn abre a las 18:00 con entrada gratuita hasta las 23:00, y despu\u00e9s la acci\u00f3n se traslada al interior, al \u00edntimo club Akasha con capacidad para 300 personas, donde contin\u00faa hasta altas horas de la madrugada. <\/p>\n<p>La fiesta se nutre de una gran cantera de talentos de la m\u00fasica electr\u00f3nica, con residentes e invitados que abarcan desde el deep house al techno mel\u00f3dico y todo lo que hay entre medias. La transici\u00f3n del jard\u00edn al club da a cada noche un arco natural, empezando de forma relajada al aire libre antes de intensificarse para una sesi\u00f3n nocturna en toda regla. Con DJs como Michael Mayer, Nick Warren y Guy J en el cartel, Supernova ofrece constantemente una programaci\u00f3n de calidad sin los precios de los grandes clubes.  <\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Cartel<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/igor-marijuan\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Igor Marijuan\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Igor Marijuan<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/bohem\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Bohem\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Bohem<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/cris44\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Cris44\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Cris44<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/guy-j\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Guy J\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Guy J<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/mariano-mellino\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Mariano Mellino\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Mariano Mellino<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Igor Marijuan<br \/>\nBohem (en directo)<br \/>\nCris44<br \/>\nGuy J<br \/>\nMariano Mellino<\/p>\n","protected":false},"template":"","wcs-type":[3815,3949,3958],"dj":[10016,14038,14039,14040,14041],"class_list":["post-1157183","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-saturday","wcs-type-supernova","wcs-type-3958","wcs-room-akasha","dj-mariano-mellino","dj-guy-j","dj-bohem","dj-igor-marijuan","dj-cris44"],"acf":[],"_wcs_timestamp":"1780164000","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/class\/1157183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/media\/574978"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/media?parent=1157183"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/wcs-type?post=1157183"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/dj?post=1157183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}