{"id":1149827,"date":"2026-04-23T17:44:51","date_gmt":"2026-04-23T16:44:51","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/toy-room-lio-2026-09-09\/"},"modified":"2026-04-23T17:44:51","modified_gmt":"2026-04-23T16:44:51","slug":"toy-room-lio-2026-09-09","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/es\/event\/toy-room-lio-2026-09-09\/","title":{"rendered":"Toy Room"},"content":{"rendered":"<p>Toy Room llega a L\u00edo cada mi\u00e9rcoles de mayo a septiembre de 2026, trayendo su marca global de noches de house glamurosas y con inclinaci\u00f3n a las celebridades al puerto de Ibiza. Conocido por sus residencias en Londres y Dub\u00e1i, Toy Room se inclina por el vocal y tech house con bailarines, una gran producci\u00f3n y un p\u00fablico vestido para la ocasi\u00f3n. El ambiente de L\u00edo sube la apuesta con vistas al mar, cenas tard\u00edas que se convierten en club y la terraza al aire libre que se llena a medida que la noche alcanza su punto \u00e1lgido. Espera residentes rotatorios y DJs invitados durante toda la temporada, cubriendo el punto dulce entre los grandes \u00e9xitos para cantar a coro y los cortes de house m\u00e1s cre\u00edbles. L\u00edo es \u00edntimo en comparaci\u00f3n con las superdiscotecas, por lo que las mesas se agotan r\u00e1pidamente y la pista de baile permanece llena. Una opci\u00f3n para las noches de mi\u00e9rcoles cuando buscas elegancia, palmeras y una producci\u00f3n adecuada sin la escala de un almac\u00e9n de Playa d\u2019en Bossa.     <\/p>\n<div class=\"wcs-lineup wcs-lineup--text\"><h3 class=\"wcs-lineup__title\">Cartel<\/h3><div class=\"wcs-lineup__excerpt\"><p>Cartel por confirmar<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cartel por confirmar<\/p>\n","protected":false},"template":"","wcs-type":[3812,3958,426],"dj":[],"class_list":["post-1149827","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-wednesday","wcs-type-3958","wcs-type-toy-room","wcs-room-lio"],"acf":[],"_wcs_timestamp":"1788998100","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/class\/1149827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/media\/583308"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/media?parent=1149827"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/wcs-type?post=1149827"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/dj?post=1149827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}