{"id":1123332,"date":"2026-03-10T12:51:02","date_gmt":"2026-03-10T12:51:02","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/solomun-outdoor-destino-2026-07-30\/"},"modified":"2026-03-10T12:51:02","modified_gmt":"2026-03-10T12:51:02","slug":"solomun-outdoor-destino-2026-07-30","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/es\/event\/solomun-outdoor-destino-2026-07-30\/","title":{"rendered":"Solomun Outdoor"},"content":{"rendered":"<p>Solomun Outdoor trae al selector bosnio-alem\u00e1n a Destino Five Ibiza para cuatro sesiones diurnas al aire libre presentadas por Pacha Icons. Lejos de su legendaria residencia de los domingos por la noche, Solomun +1 en Pacha, estos eventos junto a la piscina ofrecen una energ\u00eda totalmente diferente: ba\u00f1ada por el sol y relajada, pero con la misma selecci\u00f3n impecable de temas que ha convertido a Solomun en uno de los DJs m\u00e1s solicitados del planeta. El enclave de Destino sobre el acantilado con vistas a la bah\u00eda de Talamanca ofrece un escenario impresionante para tardes de house mel\u00f3dico y techno.  <\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Cartel<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/solomun\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2022\/09\/solomun-dj-150x150.jpeg\" alt=\"Solomun\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Solomun<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Solomun<br \/>\nLine Up por confirmar<\/p>\n","protected":false},"template":"","wcs-type":[3958,8885,396,3813],"dj":[4465],"class_list":["post-1123332","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-3958","wcs-type-solomun-outdoor","wcs-type-featured","wcs-type-thursday","wcs-room-destino","dj-solomun"],"acf":[],"_wcs_timestamp":"1785427200","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/class\/1123332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/media\/1089186"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/media?parent=1123332"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/wcs-type?post=1123332"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/dj?post=1123332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}