{"id":1111695,"date":"2026-02-05T16:34:47","date_gmt":"2026-02-05T16:34:47","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/rb-affair-ibiza-rocks-2026-05-03\/"},"modified":"2026-03-25T19:15:25","modified_gmt":"2026-03-25T19:15:25","slug":"rb-affair-ibiza-rocks-2026-05-03","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/es\/event\/rb-affair-ibiza-rocks-2026-05-03\/","title":{"rendered":"R&amp;B Affair"},"content":{"rendered":"<p>R&amp;B Affair trae ritmos suaves y vibraciones sensuales al Ibiza Rocks Pool Club todos los domingos del verano de 2026.<\/p>\n<p>Sum\u00e9rgete en una banda sonora conmovedora junto a la piscina con himnos atemporales de R&amp;B y melod\u00edas lentas modernas, desde Destiny\u2019s Child y TLC hasta SZA, Tyla y Frank Ocean. Es tu escapada semanal de los ritmos machacones y una celebraci\u00f3n del ritmo, el soul y la potencia vocal pura. <\/p>\n<p>Ya sea que te balancees junto a la piscina o cantes a grito pelado cada palabra, esta es tu invitaci\u00f3n a sentir cada ritmo y perderte en la m\u00fasica. Los domingos ahora son mucho m\u00e1s tranquilos. <\/p>\n<div class=\"wcs-lineup wcs-lineup--text\"><h3 class=\"wcs-lineup__title\">Cartel<\/h3><div class=\"wcs-lineup__excerpt\"><p>DJs residentes<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>DJs residentes<\/p>\n","protected":false},"template":"","wcs-type":[2947,3816,3958,195],"dj":[],"class_list":["post-1111695","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-rb-affair","wcs-type-sunday","wcs-type-3958","wcs-type-pool-party","wcs-room-ibiza-rocks"],"acf":[],"_wcs_timestamp":"1777824000","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/class\/1111695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/media\/1107167"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/media?parent=1111695"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/wcs-type?post=1111695"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/dj?post=1111695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}