{"id":1108656,"date":"2026-02-05T16:15:44","date_gmt":"2026-02-05T16:15:44","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/lovejuice-o-beach-2026-06-29\/"},"modified":"2026-05-28T09:47:21","modified_gmt":"2026-05-28T08:47:21","slug":"lovejuice-o-beach-2026-06-29","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/es\/event\/lovejuice-o-beach-2026-06-29\/","title":{"rendered":"LoveJuice"},"content":{"rendered":"<p>La sensaci\u00f3n global LoveJuice aterriza en O Beach Ibiza por primera vez en 2026 con cinco fechas exclusivas de m\u00fasica house pura y que te har\u00e1 sentir bien. Conocida por su ambiente vibrante y su producci\u00f3n de clase mundial, LoveJuice se ha convertido en la marca de fiestas preferida desde Marbella hasta Dub\u00e1i, y ahora trae su energ\u00eda inigualable a la Isla Blanca. <\/p>\n<p>Espera vibraciones estimulantes, ritmos ba\u00f1ados por el sol y una pista de baile llena de gente guapa celebrando la vida junto a la piscina. No pierdas la oportunidad de vivir la fiesta votada como la fiesta en la piscina n\u00famero 1 del mundo, ahora por fin en Ibiza. \u00a1Deja que fluya el LoveJuice!  <\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Cartel<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/armand-van-helden\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2025\/07\/armand-van-helden-150x150.jpg\" alt=\"Armand Van Helden\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Armand Van Helden<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/sammy-porter\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Sammy Porter\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Sammy Porter<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/george-mensah\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"George Mensah\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">George Mensah<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Armand Van Helden<br \/>\nSammy Porter<br \/>\nGeorge Mensah<\/p>\n","protected":false},"template":"","wcs-type":[195,2946,3810,3958],"dj":[8923,15639,15641],"class_list":["post-1108656","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-pool-party","wcs-type-lovejuice","wcs-type-monday","wcs-type-3958","wcs-room-o-beach","dj-armand-van-helden","dj-george-mensah","dj-sammy-porter"],"acf":[],"_wcs_timestamp":"1782738000","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/class\/1108656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/media\/993262"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/media?parent=1108656"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/wcs-type?post=1108656"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/dj?post=1108656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}