{"id":1098234,"date":"2026-02-03T11:44:40","date_gmt":"2026-02-03T11:44:40","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/aftersun-boat-party-playa-den-bossa-boat-parties-2026-08-01\/"},"modified":"2026-02-05T10:14:57","modified_gmt":"2026-02-05T10:14:57","slug":"aftersun-boat-party-playa-den-bossa-boat-parties-2026-08-01","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/es\/event\/aftersun-boat-party-playa-den-bossa-boat-parties-2026-08-01\/","title":{"rendered":"Aftersun Boat Party"},"content":{"rendered":"<p>Aftersun vuelve en 2026, y sigue siendo la nueva Boat Party \/ Fiesta en Barco m\u00e1s popular de Ibiza <\/p>\n<p>\u00danete a m\u00e1s de 300 amantes de la fiesta en un crucero con todo incluido al atardecer que no olvidar\u00e1s, zarpando desde Playa d\u2019en Bossa hasta seis veces por semana durante todo el verano.<\/p>\n<p>Prep\u00e1rate para un ambiente continuo con m\u00fasica incre\u00edble, barra libre de cerveza y sangr\u00eda, una refrescante parada para nadar y asientos en primera fila para la ic\u00f3nica puesta de sol de Ibiza, todo ello con un p\u00fablico animado y una energ\u00eda inigualable.<\/p>\n<p>Las entradas solo est\u00e1n disponibles online: \u00a1asegura la tuya ahora antes de que se agoten!<\/p>\n<h4><div class=\"wcs-lineup wcs-lineup--text\"><h3 class=\"wcs-lineup__title\">Cartel<\/h3><div class=\"wcs-lineup__excerpt\"><p>DJs residentes<\/p>\n<\/div><\/div><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>DJs residentes<\/p>\n","protected":false},"template":"","wcs-type":[1537,3815,3958,308],"dj":[],"class_list":["post-1098234","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-aftersun-boat-party","wcs-type-saturday","wcs-type-3958","wcs-type-boat-party","wcs-room-playa-den-bossa-boat-parties"],"acf":[],"_wcs_timestamp":"1785608100","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/class\/1098234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/media\/994000"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/media?parent=1098234"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/wcs-type?post=1098234"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/dj?post=1098234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}