{"id":1095044,"date":"2026-02-03T11:19:34","date_gmt":"2026-02-03T11:19:34","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/ibiza-boat-club-playa-den-bossa-boat-parties-2026-05-30\/"},"modified":"2026-02-05T09:16:03","modified_gmt":"2026-02-05T09:16:03","slug":"ibiza-boat-club-playa-den-bossa-boat-parties-2026-05-30","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/es\/event\/ibiza-boat-club-playa-den-bossa-boat-parties-2026-05-30\/","title":{"rendered":"Ibiza Boat Club"},"content":{"rendered":"<p>Puedes dejar de buscar: esta es la Boat Party \/ Fiesta en Barco de Ibiza que estabas esperando en 2026.<\/p>\n<p>La Boat Party \/ Fiesta en Barco Five Star de Ibiza Boat Club lo tiene todo: es una experiencia VIP para todos los pasajeros a bordo. \u00bfC\u00f3mo podemos describirlo?  Bueno, te sentir\u00e1s como si estuvieras en tu propio Beach Club en el mar. <\/p>\n<p>Las bebidas fluir\u00e1n, los ritmos sonar\u00e1n a tope en su sistema de sonido VOID y estar\u00e1s con otros 100 invitados levantando las manos al aire durante las 3 horas de traves\u00eda.<\/p>\n<p>Elige entre cervezas ilimitadas, sangr\u00eda y cava mientras disfrutas de la hermosa costa de Ibiza.<\/p>\n<p>Tambi\u00e9n hay comida para disfrutar: \u00bfalguien quiere paella? Y tambi\u00e9n tendr\u00e1s la oportunidad de saltar al mar y jugar con los juguetes acu\u00e1ticos. <\/p>\n<p>El Ibiza Boat Club zarpa desde Playa d\u2019en Bossa varios d\u00edas a la semana durante toda la temporada. <\/p>\n<p>Como puedes ver, somos grandes fans. Por algo es nuestra Boat Party \/ Fiesta en Barco recomendada n\u00famero 1 en Ibiza.  Tambi\u00e9n recibi\u00f3 el premio Traveler Choice de Tripadvisor la temporada pasada.<br \/>\n\u00bfA qu\u00e9 esperas? \u00a1Nos vemos a bordo!<\/p>\n<h4><div class=\"wcs-lineup wcs-lineup--text\"><h3 class=\"wcs-lineup__title\">Cartel<\/h3><div class=\"wcs-lineup__excerpt\"><p>DJs residentes<\/p>\n<\/div><\/div><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>DJs residentes<\/p>\n","protected":false},"template":"","wcs-type":[308,1453,3815,3958],"dj":[],"class_list":["post-1095044","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-boat-party","wcs-type-ibiza-boat-club","wcs-type-saturday","wcs-type-3958","wcs-room-playa-den-bossa-boat-parties"],"acf":[],"_wcs_timestamp":"1780146000","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/class\/1095044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/media\/993991"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/media?parent=1095044"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/wcs-type?post=1095044"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/dj?post=1095044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}