{"id":1091478,"date":"2026-01-30T15:38:02","date_gmt":"2026-01-30T15:38:02","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/our-house-hi-ibiza-2026-07-29\/"},"modified":"2026-06-26T11:30:42","modified_gmt":"2026-06-26T10:30:42","slug":"our-house-hi-ibiza-2026-07-29","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/es\/event\/our-house-hi-ibiza-2026-07-29\/","title":{"rendered":"Our House"},"content":{"rendered":"<p>Los productores superventas MEDUZA y James Hype regresan a H\u00ef Ibiza para otra temporada explosiva de Our House, apoder\u00e1ndose de las noches de los mi\u00e9rcoles del 27 de mayo al 30 de septiembre.<\/p>\n<p>Fusionando la energ\u00eda de un estadio con la cultura de club, Our House es una experiencia de alto octanaje donde sets que desaf\u00edan el g\u00e9nero, himnos de grandes salas y una producci\u00f3n de siguiente nivel colisionan. Prep\u00e1rate para una locura sin respiro, invitados sorpresa y una pista de baile llena de pura electricidad. Un punto culminante de la temporada de Ibiza 2026.  <\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Cartel<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/meduza\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/meduza-150x150.jpg\" alt=\"Meduza\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Meduza<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/james-hype\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/james-hype-150x150.jpg\" alt=\"James Hype\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">James Hype<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/anastazja\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Anastazja\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Anastazja<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/miane\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Miane\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Miane<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/mind-against\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Mind Against\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Mind Against<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/alok\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Alok\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Alok<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/zamna-sound-system\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Zamna Sound System\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Zamna Sound System<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/dyzen\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Dyzen\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Dyzen<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/syderal\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Syderal\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Syderal<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Meduza\u00b3<br \/>\nJames Hype<br \/>\nAnastazja<br \/>\nMiane<br \/>\nClub Room &#8211; Offweek<br \/>\nMind Against<br \/>\nAlok<br \/>\nZamna Sound System<br \/>\nDyzen B2B Syderal<\/p>\n","protected":false},"template":"","wcs-type":[307,2237,3812,3958],"dj":[12942,14785,14883,14885,5214,5216,6708,7082,9950],"class_list":["post-1091478","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-superclub","wcs-type-our-house","wcs-type-wednesday","wcs-type-3958","wcs-room-hi-ibiza","dj-anastazja","dj-zamna-sound-system","dj-dyzen","dj-syderal","dj-james-hype","dj-meduza","dj-mind-against","dj-miane","dj-alok"],"acf":[],"_wcs_timestamp":"1785365940","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/class\/1091478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/media\/1081536"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/media?parent=1091478"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/wcs-type?post=1091478"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/dj?post=1091478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}